{"id":3206,"date":"2021-07-14T22:53:02","date_gmt":"2021-07-14T22:53:02","guid":{"rendered":"https:\/\/taipeirevista.com\/?p=3206"},"modified":"2021-12-18T14:27:27","modified_gmt":"2021-12-18T14:27:27","slug":"los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje","status":"publish","type":"post","link":"https:\/\/taipeirevista.com\/index.php\/2021\/07\/14\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\/","title":{"rendered":"Los criterios constructivos. Entrevista a Alejandro Carrillo Penovi, docente de montaje"},"content":{"rendered":"\n<p><em>Alejandro Carrillo Penovi es egresado del Profesorado en Direcci\u00f3n Cinematogr\u00e1fica de la Universidad del Cine (FUC), docente, y editor de los largometrajes <\/em>El aura<em> (2005), <\/em>La se\u00f1al<em> (2007),<\/em> Igualita a m\u00ed<em> (2010), <\/em>La chica del sur <em>(2012), <\/em>El clan<em> (2015), <\/em>Piazzolla, los a\u00f1os del tibur\u00f3n<em> (2018) y <\/em>La casa de Arg\u00fcello<em> (2018), entre otros. Obtuvo dos nominaciones por Mejor Montaje para el C\u00f3ndor de Plata y una para el Premio Sur. Lo entrevistamos para la secci\u00f3n <strong>Archivo docente<\/strong><\/em> <em>de<\/em> Taipei<em>, enfoc\u00e1ndonos en su experiencia como docente de montaje en la ENERC<sup><a href=\"#nota1\" data-type=\"internal\" data-id=\"#nota1\">1<\/a><\/sup><\/em>.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"has-text-align-right has-small-font-size\"><span style=\"color:#52585d\" class=\"has-inline-color\"><strong><strong>ARCHIVO DOCENTE #<\/strong><\/strong>2<\/span><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Milagros Porta: \u00bfC\u00f3mo llegaste al montaje?<\/strong><\/p>\n\n\n\n<p>Alejandro Carrillo Penovi: Al cine por decantaci\u00f3n, supongo. Porque era un \u00e1rea en la que me parec\u00eda que no hac\u00eda falta elegir qu\u00e9 estudiar, una disciplina que integraba un mont\u00f3n de otras disciplinas. Abr\u00eda un campo de conocimientos muy amplio, [necesario] para acometer la creaci\u00f3n cinematogr\u00e1fica. Hab\u00eda que saber de fotograf\u00eda, de m\u00fasica, de guion, de relato, de texto, de lo que sea. Eso me result\u00f3 muy atractivo. No fue una decisi\u00f3n tan consciente. Con Bruno Stagnaro hac\u00edamos un programa de video en la secundaria, y yo creo que una vez que ves el <em>power <\/em>del medio, ya como adolescente, los dos entendimos que era por ah\u00ed. Y ya como estudiantes [de cine], Bruno inmediatamente se larg\u00f3 a dirigir, como que inmediatamente para \u00e9l era la direcci\u00f3n, y yo pensaba: \u201cBueno, por ah\u00ed el montaje puede ser una buena forma de aprender y de prepararse para dirigir\u201d. Y me encontr\u00e9 con una disciplina tan absorbente, tan amplia, tan interesante y tan intrincada, que eso que originalmente en mi mente era un camino hacia la direcci\u00f3n, se convirti\u00f3 en un fin en s\u00ed mismo. Se convirti\u00f3 en un destino. B\u00e1sicamente, llego al montaje pensando que es lo espec\u00edfico del cine. En ese momento no lo ten\u00eda tan consciente, pero llego al montaje por una vocaci\u00f3n ling\u00fc\u00edstica, por decirlo as\u00ed, porque me di cuenta que el montaje comprend\u00eda criterios gramaticales, criterios de construcci\u00f3n ling\u00fc\u00edstica del cine. Y debo decir la verdad: llego al montaje por una persona, por un maestro, que es Miguel P\u00e9rez, que realmente sistematiza, en su did\u00e1ctica, el conocimiento para poder editar. No solo para poder editar: el conocimiento de la gram\u00e1tica cinematogr\u00e1fica. Gracias a un gran maestro en t\u00e9rminos pedag\u00f3gicos, de did\u00e1ctica. Como ese maestro era realmente una persona que ten\u00eda capacidad de ense\u00f1ar, y esa ense\u00f1anza se cursaba a trav\u00e9s de una materia que era el montaje, eso tambi\u00e9n influenci\u00f3 much\u00edsimo mi atracci\u00f3n hacia el montaje como disciplina. Es decir, yo me sent\u00ed atra\u00eddo por una persona que pod\u00eda ense\u00f1ar, que pod\u00eda dar conocimiento de una manera muy sistematizada, muy prolija, muy clara, muy <em>n\u00edtida<\/em>. Y eso&#8230; no s\u00e9 si a todo el mundo, pero a m\u00ed, que necesitaba sentir que aprend\u00eda, por ah\u00ed una ense\u00f1anza m\u00e1s l\u00edrica, m\u00e1s impresionista \u2014que era la que tambi\u00e9n predominaba y la que sigue predominando en la ense\u00f1anza cinematogr\u00e1fica\u2014 se me hac\u00eda poco s\u00f3lida, poco aprehensible. Y de pronto con alguien que bajaba y armaba una did\u00e1ctica, dec\u00eds: \u201cEsto es. Es por ac\u00e1\u201d. Pero bueno, eso es evidentemente una cuesti\u00f3n personal, porque claramente hay gente que ha recibido esa clase de did\u00e1ctica y de ense\u00f1anza de una manera muy lejana y fr\u00eda, o no se ha vinculado, y sin embargo recuerda como personajes, como referentes de su primera educaci\u00f3n cinematogr\u00e1fica a docentes o a profesionales que ten\u00edan un abordaje mucho m\u00e1s l\u00edrico respecto de c\u00f3mo transmitir la pasi\u00f3n por el cine. Y bueno, nadie es \u201ctodo para todes\u201d. As\u00ed que en mi caso personal se dio as\u00ed: una necesidad de aprender, una persona que sab\u00eda ense\u00f1ar y que se hab\u00eda preocupado mucho \u2014y que se preocupa mucho\u2014 por c\u00f3mo ense\u00f1ar, por c\u00f3mo transmitir, por c\u00f3mo sistematizar, y ese acto de amor hacia el otre fue lo que me hizo enamorarme en primera instancia del montaje. Y una vez que entr\u00e9 ya quise seguir por ah\u00ed. As\u00ed que bueno, ese es m\u00e1s o menos el redondeo de la historia.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/22281712_10213480300378098_4739885660455853021_n.jpg\" alt=\"\" class=\"wp-image-3208\" width=\"614\" height=\"376\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/22281712_10213480300378098_4739885660455853021_n.jpg 960w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/22281712_10213480300378098_4739885660455853021_n-300x184.jpg 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/22281712_10213480300378098_4739885660455853021_n-768x470.jpg 768w\" sizes=\"(max-width: 614px) 100vw, 614px\" \/><figcaption>Alejandro Penovi<\/figcaption><\/figure>\n\n\n\n<p><strong>MP: \u00bfY cre\u00e9s que la presencia de este profesor influy\u00f3 tambi\u00e9n en tu pr\u00e1ctica docente?<\/strong><\/p>\n\n\n\n<p>ACP: Absolutamente, claro. Una cosa que aprendimos con Iv\u00e1n en nuestra cursada com\u00fan en el profesorado de la FUC<sup><a href=\"#nota2\">2<\/a><\/sup> es que tu propia biograf\u00eda como alumno es determinante de tu forma de encarar una clase. Porque tu experiencia como alumno y tus modelos docentes son los que configuran la forma en que vos vas a encarar una clase. Eso es absolutamente inevitable. Y s\u00ed, yo estoy seguro de que eso corre por un lado. Eso ser\u00eda como la parte, si se quiere, m\u00e1s general, espiritual o principista. Pero en la cuesti\u00f3n m\u00e1s pr\u00e1ctica yo empiezo a dar clases de la mano de Miguel, tambi\u00e9n. No es que yo me mando a dar clases. Mis primeras clases de montaje las doy porque me llama Miguel y me dice: \u201cNecesito que des montaje\u201d. Y yo ah\u00ed le digo: \u201c\u00bfPero c\u00f3mo hago?\u201d. Y ah\u00ed recepto (sic), literalmente, los apuntes de guion. Y despu\u00e9s voy a sus clases y refresco mis conocimientos; no solo mis conocimientos de montaje, [tambi\u00e9n] mis conocimientos did\u00e1cticos. Los refresco directamente de la fuente. Entonces, no es que yo hice una investigaci\u00f3n. Todo eso lo hizo Miguel y yo fui y soy un aut\u00e9ntico disc\u00edpulo de \u00e9l. Y lo que aplico en las clases que doy es \u201cMiguel P\u00e9rez\u201d. Es decir, yo soy como una especie de sucursal de Miguel, no es que tengo un desarrollo propio. Seguramente porque Miguel mismo, la primera vez que me convoc\u00f3, me dijo \u201cnecesito que des lo que doy yo\u201d y me gui\u00f1\u00f3 un ojo: \u201cCon las cosas que vos le vas a poner\u201d. Es inevitable. No es que doy la misma clase. Primero porque no puedo, porque no tengo la sistematizaci\u00f3n que tiene \u00e9l, pero los contenidos de lo que yo doy en un 90% son contenidos desarrollados por Miguel. Entonces, s\u00ed: la respuesta es \u201cs\u00ed\u201d a gritos. S\u00ed en t\u00e9rminos espirituales, s\u00ed en t\u00e9rminos estrictamente pragm\u00e1ticos.&nbsp;<\/p>\n\n\n\n<p><strong>Iv\u00e1n Bustinduy: Y en relaci\u00f3n a esto, y tambi\u00e9n pensando en la formaci\u00f3n que hicimos juntos en el profesorado espec\u00edfico en ense\u00f1anza del cine en la FUC, \u00bfpens\u00e1s que incidi\u00f3 de alguna manera en tu labor docente, que ya ven\u00edas construyendo desde hace a\u00f1os?<\/strong><\/p>\n\n\n\n<p>ACP: Much\u00edsimo. Sobre todo la primera reacci\u00f3n es angustia y desesperaci\u00f3n, porque mientras uno no se hace cargo del bagaje docente, del conocimiento did\u00e1ctico y del conocimiento pedag\u00f3gico, mientras uno dice \u201cyo soy un simple editor puesto a ense\u00f1ar\u201d, uno puede alegar inocencia de ciertas cosas (\u201cNo, no, yo esto no lo s\u00e9, yo esto no lo podr\u00eda saber, yo edito\u201d). Cuando conscientemente te hac\u00e9s cargo de tu posici\u00f3n docente, y de que la docencia es una especializaci\u00f3n y es una actividad espec\u00edfica, empez\u00e1s a no poder evitar medir tu <em>performance <\/em>y tu construcci\u00f3n con la vara pedag\u00f3gica, con la vara de una l\u00f3gica did\u00e1ctica. Y la primera impresi\u00f3n, cuando hac\u00e9s eso, es de una profunda decepci\u00f3n. Es decir: \u201cYo no estoy sistematizando, no estoy haciendo una clase dialogada\u2026\u201d. A fines del a\u00f1o pasado dimos el examen de la \u00faltima materia, la residencia, la pedagog\u00eda espec\u00edfica del cine, y no he tenido tiempo todav\u00eda de sentarme a reevaluar mi programa a la luz de todos los conocimientos y criterios que incorporamos durante la cursada. El tema es que, si te lo tom\u00e1s en serio, es muy riguroso y muy costoso. Realmente ten\u00e9s que invertir una cantidad de tiempo muy considerable. Y, cuando uno dedica su tiempo vital a ganar plata editando contenido profesional, no te queda tanto tiempo disponible para dedicarle a tu pr\u00e1ctica docente. Esa es la m\u00e1s concreta realidad. Entonces, \u00bfqu\u00e9 voy a hacer con todo eso? Cuando me tenga que sentar a reformular voy a tener que ver qu\u00e9 hago. Porque hay muchas cosas para aplicar. De pronto, te desayun\u00e1s que hay un mont\u00f3n de ideas que uno tiene sobre lo que uno hace, que es el montaje, pero hay que hacer un primer paso que es traducir eso. La famosa transposici\u00f3n did\u00e1ctica: traducir eso a un formato que le sirva a los dem\u00e1s para aprehender y asimilar esos conceptos y, adem\u00e1s, c\u00f3mo sistematizar eso. La ventaja que tuve yo es que, en nuestro caso, el caso de la \u201cescuela P\u00e9rez\u201d, Miguel hizo eso muy bien intuitivamente. Entonces nosotros, los que agarramos su contenido en general, no necesitamos moverlo tanto. Pero la desventaja es que, si lo ten\u00e9s que volver a hacer para vos mismo, te das cuenta de todo el trabajo que hizo Miguel durante tantos a\u00f1os. Entonces es una monta\u00f1a muy grande que hay que escalar. Y bueno, habr\u00e1 que escalarla, y lo \u00fanico que puedo decir es que ahora no tengo espacio para hacerme el tonto.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.45.49.791-1-1024x576.jpg\" alt=\"\" data-id=\"3227\" data-full-url=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.45.49.791-1.jpg\" data-link=\"https:\/\/taipeirevista.com\/?attachment_id=3227\" class=\"wp-image-3227\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.45.49.791-1-1024x576.jpg 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.45.49.791-1-300x169.jpg 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.45.49.791-1-768x432.jpg 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.45.49.791-1.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.00.478-1-1024x576.jpg\" alt=\"\" data-id=\"3228\" data-full-url=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.00.478-1.jpg\" data-link=\"https:\/\/taipeirevista.com\/?attachment_id=3228\" class=\"wp-image-3228\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.00.478-1-1024x576.jpg 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.00.478-1-300x169.jpg 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.00.478-1-768x432.jpg 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.00.478-1.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.11.887-1-1024x576.jpg\" alt=\"\" data-id=\"3229\" data-full-url=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.11.887-1.jpg\" data-link=\"https:\/\/taipeirevista.com\/?attachment_id=3229\" class=\"wp-image-3229\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.11.887-1-1024x576.jpg 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.11.887-1-300x169.jpg 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.11.887-1-768x432.jpg 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.11.887-1.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.13.438-1-1024x576.jpg\" alt=\"\" data-id=\"3230\" data-full-url=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.13.438-1.jpg\" data-link=\"https:\/\/taipeirevista.com\/?attachment_id=3230\" class=\"wp-image-3230\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.13.438-1-1024x576.jpg 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.13.438-1-300x169.jpg 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.13.438-1-768x432.jpg 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.13.438-1.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.21.721-1-1024x576.jpg\" alt=\"\" data-id=\"3231\" data-full-url=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.21.721-1.jpg\" data-link=\"https:\/\/taipeirevista.com\/?attachment_id=3231\" class=\"wp-image-3231\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.21.721-1-1024x576.jpg 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.21.721-1-300x169.jpg 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.21.721-1-768x432.jpg 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.21.721-1.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.26.350-1024x576.jpg\" alt=\"\" data-id=\"3232\" data-full-url=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.26.350.jpg\" data-link=\"https:\/\/taipeirevista.com\/?attachment_id=3232\" class=\"wp-image-3232\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.26.350-1024x576.jpg 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.26.350-300x169.jpg 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.26.350-768x432.jpg 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/El-aura-Fabian-Bielinsky-2005WEB-HD-PdB.mkv_snapshot_01.46.26.350.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><figcaption class=\"blocks-gallery-caption\"><em>El aura<\/em> (Fabi\u00e1n Bielinsky, 2005)<\/figcaption><\/figure>\n\n\n\n<p><strong>IB: En relaci\u00f3n a esto que contabas, de la falta de tiempo estando en un momento avanzado de tu carrera, en el que est\u00e1s con mucho trabajo profesional, \u00bfcre\u00e9s que una formaci\u00f3n docente, para un profesor o una profesora de cine que est\u00e1 arrancando, es aconsejable? \u00bfPuede tener alg\u00fan tipo de relevancia en una instancia en la que se puede dar ese tiempo?<\/strong><\/p>\n\n\n\n<p>ACP: Absolutamente. Es que ahora me parece indispensable. Mi dilema es \u00e9ste: una de las cosas que vimos en el profesorado es esta cuesti\u00f3n de la profesionalizaci\u00f3n de la docencia. Es decir: docentar, ser docente, es una especialidad tan concreta como ser neurocirujano o neurocirujana. Hay un mont\u00f3n de saberes de la docencia, y adem\u00e1s est\u00e1 el oficio docente. Resulta dif\u00edcil conciliar el mundo de la praxis cinematogr\u00e1fica, que es el mundo de rodar, de escribir, de estar ah\u00ed, de estar sentado ocho horas por d\u00eda, con el mundo de la praxis docente. No son muchas las personas que pueden tener ambos mundos y que pueden conciliar ambos mundos con eficiencia. Quiero decir esto: resulta dif\u00edcil encontrar grandes profesionales que al mismo tiempo tengan una larga trayectoria docente. Esa es mi lectura. Probablemente me est\u00e9 equivocando, pero tengo la sensaci\u00f3n de que es as\u00ed porque, justamente, es muy dif\u00edcil poner tu energ\u00eda en las dos canchas: en la cancha de responder a las demandas de las producciones de cine o de audiovisual, que requieren una dedicaci\u00f3n muy fuerte, y al mismo tiempo responder a las demandas de una buena formaci\u00f3n docente.&nbsp;<\/p>\n\n\n\n<p>Yendo a la pregunta: s\u00ed, mi sensaci\u00f3n es que si yo hubiera tenido estos conocimientos que incorpor\u00e9 reci\u00e9n hace tres a\u00f1os, sobre la dimensi\u00f3n docente de un profesional del cine, seguramente hubiera encarado mi pr\u00e1ctica docente mucho antes. Pero esto es un contraf\u00e1ctico, porque cuando estaba estudiando cine yo no quer\u00eda ser docente de cine, quer\u00eda ser cineasta. Y, para m\u00ed, hab\u00eda una clara distinci\u00f3n entre los docentes de cine y los cineastas. Los docentes de cine no eran cineastas. Era raro: hab\u00eda claramente docentes de cine cineastas, pero no eran la mayor\u00eda. La mayor\u00eda de los docentes de cine ten\u00edan trabajo porque normalmente vos acced\u00edas a la docencia cinematogr\u00e1fica a trav\u00e9s de un curr\u00edculum profesional, que eso es lo que te daba a vos la certeza de que la persona que estaba ah\u00ed ten\u00eda cierta autoridad para impartir una materia. Pero eso era en los noventa, 1996-97. Ahora empieza a cambiar ese paradigma, y empieza a aparecer esta cuesti\u00f3n de la docencia cinematogr\u00e1fica casi como una cuesti\u00f3n espec\u00edfica. Y, al mismo tiempo, tambi\u00e9n queda develado que no necesariamente un buen profesional, o un profesional excelente, de una disciplina audiovisual, da como resultado un buen docente. Puede dar como resultado un gran componente de <em>marketing <\/em>para atraer personas a escucharlo hablar, pero no garantiza necesariamente una buena docencia. Creo que todos podemos recordar en nuestra trayectoria como alumnes a extraordinarios y extraordinarias docentes que no eran profesionales destacados, pero que sin embargo nos abrieron la puerta de lo que era hacer cine. Entonces es una sensaci\u00f3n ambigua: \u00bfqu\u00e9 se hace con un conocimiento de pr\u00e1ctica docente cuando todav\u00eda vos no quer\u00e9s ser docente? Al mismo tiempo, al rev\u00e9s: \u00bfpor qu\u00e9 ten\u00e9s que ser experto y un profesional destacado para ense\u00f1ar? Hay una serie de preguntas y respuestas, y una serie de nebulosas que a m\u00ed no me quedan del todo claras.&nbsp;<\/p>\n\n\n\n<p>Yo s\u00e9 que hice el profesorado cuando tuve consciencia de que ya estaba dando clases. Es decir, yo s\u00e9 que entr\u00e9 al profesorado cuando ya me sent\u00eda en una posici\u00f3n docente, con capacidad de ocupar ese espacio. Pero debo admitir que no me hubiera sentido habilitado a ser docente sin tener esa trayectoria. Pero eso es por c\u00f3mo soy yo; tengo ese est\u00e1ndar, donde siento que para poder ense\u00f1ar algo tan complejo como el montaje ten\u00e9s que tener oficio. Y eso es una definici\u00f3n tremenda sobre la posici\u00f3n docente en cine. Creo que hay que tener oficio para ense\u00f1ar algo tan pr\u00e1ctico y tan complejo como hacer cine, pero al mismo tiempo vos pod\u00e9s tener un mont\u00f3n de oficio y no saber c\u00f3mo ense\u00f1ar. Entonces, \u00bfqu\u00e9 hacer? Bueno, en mi caso, y es una cosa personal, primero hice el oficio de hacer, y despu\u00e9s me puse a investigar el oficio de ense\u00f1ar. Y creo que debe ser el camino que hizo Miguel tambi\u00e9n. Voy a a\u00f1adir algo: las materias pedag\u00f3gicas me abrieron un mundo, un universo que estaba ah\u00ed [esper\u00e1ndome]. Yo no sab\u00eda qu\u00e9 tan importante era para mi vida y para mi filosof\u00eda de vida la cuesti\u00f3n de ponerme a pensar en t\u00e9rminos pedag\u00f3gicos sobre la ense\u00f1anza del cine. Aplicarle todo ese corpus te\u00f3rico, toda esa visi\u00f3n, toda esa perspectiva \u2014esa es la palabra: aplicarle la perspectiva pedag\u00f3gica a la idea de hacer cine. Yo le\u00eda a [Alain] Bergala y me enojaba: \u201c\u00bfQu\u00e9 est\u00e1 diciendo este tipo?\u201d. Me agarraba por otro lado, porque si te pon\u00e9s a pensar: \u00bfpor qu\u00e9 te enoj\u00e1s? Bueno, porque est\u00e1s muy comprometido. Si no te compromete el tema, un enunciado no te puede producir incomodidad o alterarte, y yo por momentos me alteraba: \u00bfqu\u00e9 est\u00e1 escribiendo este muchacho? Creo que lo lindo es eso: en un momento se te abre eso y te atrapa, lisa y llanamente te atrapa. Es como una segunda puerta que se me ha abierto ahora, y la verdad es que me copa ser profesor oficialmente, me copa tener un conocimiento espec\u00edfico de este mundo. Y me copar\u00eda poder seguir abri\u00e9ndolo. Y cuando yo me siento y le hablo a colegas de esto&#8230; porque esto por ejemplo le pasa a Vero Cura<sup><a href=\"#nota3\" data-type=\"internal\" data-id=\"#nota3\">3<\/a><\/sup>, que es amiga m\u00eda y una de esas profesionales que es buen\u00edsima docente y adem\u00e1s lo disfruta. Y cuando yo me siento a hablar con ella y le digo \u201cvos sab\u00e9s que agarr\u00e9 e hice el profesorado\u201d y le empiezo a nombrar autores, me dice: \u201cPasame ese libro, pasame ese libro\u201d. Es decir, quienes estamos en la docencia estamos en un juego, y quienes nos la tomamos en serio, estamos en un juego donde esas cosas te comprometen a un nivel \u00e9tico, espiritual y hasta te dir\u00eda est\u00e9tico. Claramente hay una est\u00e9tica de la docencia. Y me parece que eso es lo apasionante de que te abran esa puerta. La est\u00e9tica es conocimiento. Vos pod\u00e9s empezar a hablar de algo en t\u00e9rminos est\u00e9ticos en la medida en que empez\u00e1s a conocer el fen\u00f3meno. Adem\u00e1s, vos te das cuenta: los grandes docentes de tu vida ten\u00edan algo bello, algo del orden de la belleza en su <em>performance<\/em>.<\/p>\n\n\n\n<p><strong>IB: Sumo algo en relaci\u00f3n a esto de la est\u00e9tica de la ense\u00f1anza, porque adem\u00e1s de ser, como toda est\u00e9tica, forma, me parece que hay algo que es muy similar con ese momento en el cual uno aprende cine, que nunca termina; ese momento en el cual empez\u00e1s a reconocer, o a ser consciente, de decisiones que ya tom\u00e1s. Sos consciente de decisiones que ya tomabas, pero que no sab\u00edas que eran decisiones. Entonces empez\u00e1s a vincular o evaluar esas decisiones con respecto a objetivos, a prop\u00f3sitos. Y tambi\u00e9n desde un lugar pol\u00edtico o est\u00e9tico; est\u00e9tico con respecto al cine y pol\u00edtico con respecto a la ense\u00f1anza, y en particular a la ense\u00f1anza del cine.<\/strong><\/p>\n\n\n\n<p>ACP: S\u00ed, tal cual, es as\u00ed. Se abre un universo, y de pronto te sent\u00eds tan chiquito&#8230; Porque es al rev\u00e9s: vos sent\u00edas que, si esto es ense\u00f1ar, si este espacio era ense\u00f1ar [hace con las manos un gesto de algo peque\u00f1o], yo lo ocupo. Pero de pronto vas y aprend\u00e9s \u2014que es el terror\u2014 y se hace as\u00ed [hace gesto de algo enorme]. Y el espacio de pronto se te abre y, claro, en relaci\u00f3n a ese espacio de pronto sos un alfe\u00f1ique. Es como que dec\u00eds: \u201c\u00bfy yo estaba pretendiendo dar clase?\u201d. Contra ese primer sopapo, el hecho de volver a dar clase y que las alumnas y alumnos respondan positivamente a tu pr\u00e1ctica docente te vuelve a dar clase, te la renueva. S\u00ed, es verdad, soy un alfe\u00f1ique, pero no quedo inhabilitado porque no tengo por qu\u00e9 llenar todo este espacio. Yo tengo que llenar el espacio que est\u00e1 a mi alcance, e irlo llenando de a poco y construir. Y punto. Y de ah\u00ed, para adelante. Pero s\u00ed, te abre toda una nueva dimensi\u00f3n, una nueva dimensi\u00f3n de tu paso por la vida. Y donde te encontr\u00e1s con ideas muy bellas, [por ejemplo] las ideas de darle la bienvenida a las nuevas generaciones, esas cosas tan lindas que le\u00edmos de pedagogos como [Philippe] Meirieu.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"556\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/Piazzolla-Los-anos-del-tiburon-Daniel-Rosenfeld-2018.mp4_snapshot_01.14.47.008-1024x556.jpg\" alt=\"\" data-id=\"3237\" data-full-url=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/Piazzolla-Los-anos-del-tiburon-Daniel-Rosenfeld-2018.mp4_snapshot_01.14.47.008.jpg\" data-link=\"https:\/\/taipeirevista.com\/?attachment_id=3237\" class=\"wp-image-3237\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/Piazzolla-Los-anos-del-tiburon-Daniel-Rosenfeld-2018.mp4_snapshot_01.14.47.008-1024x556.jpg 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/Piazzolla-Los-anos-del-tiburon-Daniel-Rosenfeld-2018.mp4_snapshot_01.14.47.008-300x163.jpg 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/Piazzolla-Los-anos-del-tiburon-Daniel-Rosenfeld-2018.mp4_snapshot_01.14.47.008-768x417.jpg 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/Piazzolla-Los-anos-del-tiburon-Daniel-Rosenfeld-2018.mp4_snapshot_01.14.47.008.jpg 1436w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"556\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/Piazzolla-Los-anos-del-tiburon-Daniel-Rosenfeld-2018.mp4_snapshot_01.14.49.111-1024x556.jpg\" alt=\"\" data-id=\"3238\" data-full-url=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/Piazzolla-Los-anos-del-tiburon-Daniel-Rosenfeld-2018.mp4_snapshot_01.14.49.111.jpg\" data-link=\"https:\/\/taipeirevista.com\/?attachment_id=3238\" class=\"wp-image-3238\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/Piazzolla-Los-anos-del-tiburon-Daniel-Rosenfeld-2018.mp4_snapshot_01.14.49.111-1024x556.jpg 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/Piazzolla-Los-anos-del-tiburon-Daniel-Rosenfeld-2018.mp4_snapshot_01.14.49.111-300x163.jpg 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/Piazzolla-Los-anos-del-tiburon-Daniel-Rosenfeld-2018.mp4_snapshot_01.14.49.111-768x417.jpg 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/Piazzolla-Los-anos-del-tiburon-Daniel-Rosenfeld-2018.mp4_snapshot_01.14.49.111.jpg 1436w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><figcaption class=\"blocks-gallery-caption\"><em>Piazzolla, los a\u00f1os del tibur\u00f3n<\/em> (Daniel Rosenfeld, 2018)<\/figcaption><\/figure>\n\n\n\n<p><strong>MP: En relaci\u00f3n a esta construcci\u00f3n que vas haciendo con tu pr\u00e1ctica, \u00bfcu\u00e1les son los temas que trabaj\u00e1s s\u00ed o s\u00ed cada a\u00f1o, en la materia que das? Es decir, \u00bfqu\u00e9 es lo fundamental, para vos, que hay que ense\u00f1ar en esa materia?<\/strong><\/p>\n\n\n\n<p>ACP: Para m\u00ed lo fundamental tiene que ver&#8230; Es una l\u00ednea muy cl\u00e1sica. Lamentablemente soy muy <em>pereciano<\/em>, muy hijo de P\u00e9rez. Miguel tiene una sistematizaci\u00f3n s\u00faper clasicista del lenguaje cinematogr\u00e1fico, donde la idea es tratar de encontrar principios rectores que organicen tu trabajo y que sean \u00fatiles. No principios para dar cuenta de un fen\u00f3meno, porque eso es Roland Barthes, Christian Metz, los analistas. No, dar cuenta del fen\u00f3meno no es el plato del d\u00eda. Entonces, lo que necesitamos son principios que organicen tu praxis, principios que organicen la praxis cotidiana, que es \u201cte tiro cuarenta tomas, constru\u00ed un relato, constru\u00ed una unidad\u201d. Y entonces me parece que lo m\u00e1s importante son estos criterios constructivos, cu\u00e1les son los criterios para construir unidades de orden superior con unidades de orden inferior. En ese sentido, me parece que lo m\u00e1s importante es entender cuestiones que tienen que ver con la progresi\u00f3n dram\u00e1tica, cuestiones que tienen que ver con las convenciones m\u00e1s elementales respecto de la gram\u00e1tica audiovisual: qu\u00e9 significan esas convenciones, por qu\u00e9 los cortes funcionan, por qu\u00e9 cortamos, cu\u00e1l es el principio que impulsa el corte, que es la acci\u00f3n paradigm\u00e1tica del lenguaje del cine.&nbsp;<\/p>\n\n\n\n<p>El lenguaje del cine tiene tres dimensiones. Una es el recorte espacial, que viene dado por el encuadre. Ah\u00ed ten\u00e9s los tama\u00f1os de plano, etc\u00e9tera. La otra es el punto de vista, que tiene que ver con el lugar desde donde vos plant\u00e1s la c\u00e1mara para producir ese recorte. Son las dos dimensiones del espacio. Y esa incorpora la cuesti\u00f3n de la puesta en escena, que claramente a nosotros, al editor o la editora, ya nos llega de alguna manera preconcebida. Entonces vos ten\u00e9s que sintonizar con ese primer acto constructivo, que es el acto constructivo del director o la directora en un rodaje. Ten\u00e9s que conocer qu\u00e9 hay ah\u00ed atr\u00e1s. Pero eso ya viene prefigurado, y es un \u00e1rea donde vos no vas a poder operar. Porque vos no vas a poder cambiar una puesta en escena y un punto de vista. Con el encuadre ten\u00e9s un poco de margen, estamos todo el tiempo achicando y agrandando, hay ciertas cositas que pod\u00e9s hacer. Pero no el punto de vista. Y frente a ese recorte, que son dos decisiones, que son <em>desde d\u00f3nde<\/em> y <em>qu\u00e9<\/em>, viene el tercer recorte, que es <em>cu\u00e1nto <\/em>y <em>cu\u00e1ndo<\/em>: el recorte temporal. Me parece que lo que uno tiene que tratar de transmitirle a quien va a editar son estos criterios constructivos b\u00e1sicos de qu\u00e9 es el encuadre, para qu\u00e9 es el encuadre y cu\u00e1l es el objetivo de todo eso: qu\u00e9 es lo que hay que tratar de producir. Y lo que hay que tratar de producir es sentido. Entonces, para producir sentido hay ciertas convenciones\u2026 En fin, para m\u00ed lo que ten\u00e9s que explicarle a quien est\u00e1 editando es por qu\u00e9 las cosas son as\u00ed, de d\u00f3nde vienen las convenciones, cu\u00e1l es el sentido de todo esto. Y un sentido que sea universal, no un sentido oculto, m\u00edstico, un sentido al alcance solo de las iniciadas y los iniciados, solo de aquellos que tienen la capacidad de percibir la profundidad de la significancia del arte cinematogr\u00e1fico que toc\u00f3 a genios como [Akira] Kurosawa, como [Andr\u00e9i] Tarkovski. No. Yo ma\u00f1ana laburo y tengo que hacer un documental para <em>Encuentro<\/em>, y tengo treinta planos, \u00bfc\u00f3mo hago? Lo mismo que hizo Kurosawa, que hizo Tarkovski, que hizo [Pier Paolo] Pasolini. Nombr\u00e1 a quien quieras, usan la misma idea: usan una c\u00e1mara, un encuadre, un punto de vista y cortan. Listo, no hay mucho que decir. \u00bfPor qu\u00e9? Porque est\u00e1n produciendo un sentido. Entonces, me parece que lo importante es transmitirle a la gente que se va a sentar, de a poco, cu\u00e1l es ese sentido. Y adem\u00e1s, saber que la idea es que si vos les transmit\u00eds esos conceptos sencillos\u2026 complicad\u00edsimos, justamente, pero muy sencillos, el que lo agarra, o la que lo agarra, sigue tirando de la piola y va solo por su camino. Es dotar a las personas que est\u00e1n ah\u00ed de un primer paso consciente, de una primera toma de consciencia de qu\u00e9 es lo que se est\u00e1 haciendo, para que a partir de ah\u00ed puedan tirar del ovillo ellas y ellos solos, y seguir su camino. Porque nadie sale de una clase de montaje sabiendo editar. Uno sale de una clase de montaje sabiendo c\u00f3mo seguir aprendiendo a editar, me parece. Es eso: qu\u00e9 es lo que tengo que seguir buscando, qu\u00e9 es lo que tengo que seguir aprendiendo. Es explicar el sentido de las convenciones de la gram\u00e1tica audiovisual: por qu\u00e9 se usaron, por qu\u00e9 triunfaron, por qu\u00e9 persistieron, y en todo caso avisar que todo esto se puede romper, porque todo esto es lenguaje cl\u00e1sico. Justamente, parte de la gracia de ense\u00f1ar clasicismo es que cuando vos quer\u00e9s producir claridad vas por lo cl\u00e1sico, y cuando vos quer\u00e9s romper la claridad y producir m\u00e1s mancha, m\u00e1s impresi\u00f3n, m\u00e1s borrosidad\u2026 la idea es ir por el otro lado.<\/p>\n\n\n\n<p><strong>IB: Y que sea una decisi\u00f3n.<\/strong><\/p>\n\n\n\n<p>ACP: Claro, exactamente. Pero est\u00e1 bueno lo que dicen todos los que te ense\u00f1an: aprend\u00e9 primero la regla constructiva, y despu\u00e9s deconstru\u00eds. Eso de aprender primero a deconstruir, no. Es muy canchero, pero qu\u00e9 s\u00e9 yo&#8230; la sensaci\u00f3n que uno tiene es que todos los locos de mierda \u2014[Jean-Luc] Godard, todos esos, en realidad lo que hicieron fue justamente romper porque ya sab\u00edan muy bien c\u00f3mo se hac\u00eda y cu\u00e1les eran las reglas que estaban trabajando. Y dijeron \u201cestamos hartos de estas reglas, vamos a producir otra clase de objetos\u201d.<\/p>\n\n\n\n<p>Un poco lo que le pas\u00f3 tambi\u00e9n a los dodecafonistas, al serialismo musical: \u201cestamos podridos de t\u00f3nica, subdominante, dominante, t\u00f3nica. A ver, rompamos un poco las reglas de la armon\u00eda tradicional, borremos el centro t\u00f3nico, empecemos a trabajar con series para que no haya un centro tonal\u201d&#8230; bueno, todo bien, no dej\u00f3 de ser un movimiento interesante, pero la verdad es que no conozco a nadie que vaya silbando por la calle <em>Wozzeck<\/em>. Capaz que s\u00ed, no s\u00e9.<\/p>\n\n\n\n<p><strong>IB: Con respecto a esto que dec\u00edas, de acercar a los estudiantes, las estudiantes, a las convenciones; que no ten\u00e9s que ser un erudito para conocerlas; \u00bften\u00e9s alg\u00fan ejercicio, por ejemplo, que te ayude a laburar alguna de esas cuestiones en detalle?&nbsp;<\/strong><\/p>\n\n\n\n<p>ACP: El ejercicio m\u00e1s interesante para m\u00ed es agarrar un crudo de cualquier secuencia profesional, en lo posible con una puesta relativamente cl\u00e1sica, y ensayar. Y ver qu\u00e9 pasa. Ese es un ejercicio muy ilustrativo, porque todas las decisiones que se toman a la hora de editar demuestran una idea, o un concepto, o un intento, y despu\u00e9s es muy claro cuando el resultado no acompa\u00f1a la idea. Es muy claro cuando yo lo que quer\u00eda era esto, pero de pronto se lo mostr\u00e1s a un grupo de gente, que son normalmente el grupo de estudiantes, y pregunt\u00e1s, y te das cuenta que no ocurri\u00f3 eso. Una de las cosas que yo trato de hacer, desde siempre, desde que empec\u00e9 con los ejercicios, es que la devoluci\u00f3n sea grupal. Y el hecho de que las propias compa\u00f1eras y compa\u00f1eros de la persona que hizo el ejercicio sean las primeras en opinar produce dos cosas: primero, allana el escenario, y pone a todo el mundo en condiciones de poder opinar y de poder decir qu\u00e9 le pas\u00f3. Porque adem\u00e1s, lo primero que yo les pido a las alumnas y alumnos cuando est\u00e1n opinando sobre trabajos de los compa\u00f1eros es que, en principio, traten de opinar desde lo que les pas\u00f3. Que no traten de opinar sobre el c\u00f3mo. Porque eso es un trabajo que tiene que resolver la persona que tom\u00f3 las decisiones. Y que reci\u00e9n en una segunda instancia, si tienen a mano una noci\u00f3n de cu\u00e1l fue la causa que les produjo esa sensaci\u00f3n, la pueden jugar, por supuesto. Pero que el primer ataque hacia la conversaci\u00f3n con quien hizo el montaje \u2014el primer enfoque\u2014 sea un enfoque desde la subjetividad de lo que pas\u00f3, de lo que se sinti\u00f3. Me parece que eso adem\u00e1s me permite a m\u00ed entrar despu\u00e9s al juego de una manera mucho m\u00e1s armoniosa, mucho menos desde una <em>auctoritas <\/em>que va a se\u00f1alar el camino correcto, porque adem\u00e1s en montaje no hay caminos correctos, hay decisiones en funci\u00f3n de objetivos. No es can\u00f3nico el montaje en ese sentido. Obedece a una decisi\u00f3n de objetivos. Y este tipo de abordaje permite llegar justamente al punto interesante, que es: \u00bfcu\u00e1l era tu objetivo? \u00bfQu\u00e9 es lo que estabas buscando? Porque de lo que podemos hablar es: qu\u00e9 tal se aviene este enfoque a este objetivo. Pero nunca perder de vista cu\u00e1l era el objetivo. Y cuando habl\u00e1s de objetivos, a veces te das cuenta de que hay una esfera de interpretaci\u00f3n de la escena que todav\u00eda no est\u00e1 resuelta. Y entonces, cuando esa esfera de la interpretaci\u00f3n no est\u00e1 resuelta, abr\u00eds la puerta por ah\u00ed y te met\u00e9s a la dimensi\u00f3n profunda, interpretativa, del sentido del lenguaje cinematogr\u00e1fico. Pero no el sentido de qu\u00e9 es lo que hay que contar, si no de qu\u00e9 es lo que tiene que pasar para que esto impacte. D\u00f3nde est\u00e1 la sustancia. Y empez\u00e1s a abrir qu\u00e9 le quiso decir este personaje a tal otro, y empez\u00e1s a decir: \u00a1el texto y el subtexto! \u00a1Y abr\u00eds esa dimensi\u00f3n! Vos no edit\u00e1s para el texto, edit\u00e1s para el subtexto tambi\u00e9n. Y cuando abr\u00eds esa dimensi\u00f3n, se abre todo un mundo para discutir.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"422\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_01.44.25.327-1024x422.jpg\" alt=\"\" data-id=\"3219\" data-full-url=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_01.44.25.327.jpg\" data-link=\"https:\/\/taipeirevista.com\/?attachment_id=3219\" class=\"wp-image-3219\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_01.44.25.327-1024x422.jpg 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_01.44.25.327-300x124.jpg 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_01.44.25.327-768x317.jpg 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_01.44.25.327-1536x634.jpg 1536w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_01.44.25.327.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"422\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_01.44.24.609-1024x422.jpg\" alt=\"\" data-id=\"3218\" data-full-url=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_01.44.24.609.jpg\" data-link=\"https:\/\/taipeirevista.com\/?attachment_id=3218\" class=\"wp-image-3218\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_01.44.24.609-1024x422.jpg 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_01.44.24.609-300x124.jpg 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_01.44.24.609-768x317.jpg 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_01.44.24.609-1536x634.jpg 1536w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_01.44.24.609.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"422\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_01.44.23.978-1024x422.jpg\" alt=\"\" data-id=\"3217\" data-full-url=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_01.44.23.978.jpg\" data-link=\"https:\/\/taipeirevista.com\/?attachment_id=3217\" class=\"wp-image-3217\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_01.44.23.978-1024x422.jpg 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_01.44.23.978-300x124.jpg 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_01.44.23.978-768x317.jpg 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_01.44.23.978-1536x634.jpg 1536w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_01.44.23.978.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><figcaption class=\"blocks-gallery-caption\"><em>The Wild Bunch<\/em> (Sam Peckinpah, 1969)<\/figcaption><\/figure>\n\n\n\n<p>Vos fijate que un ejercicio tan sonso (bueno, no es sonso, \u00bfno?), un ejercicio tan simple en apariencia como editar una escena, abre un universo. Y vos eleg\u00eds hasta d\u00f3nde lo llev\u00e1s, porque obviamente no pod\u00e9s desarrollar un universo en una clase, sobre todo cuando hay diez alumnas y alumnos que necesitan cada uno mostrar su peque\u00f1o universo. Entonces vos vas viendo hasta d\u00f3nde lo llev\u00e1s, y uno de los defectos que tengo yo como docente es que no tengo muy pautado, no tengo muy tomado todav\u00eda el <em>timing<\/em>, y a veces cuando se abre un universo que me apasiona me voy por ah\u00ed, y hasta que no lo dejo resuelto, hasta que no consigo que las chicas y los chicos detecten \u201c\u00a1ah! \u00a1Este era el cuento! \u00a1Para este lado es donde hay que explotar!\u201d, no paro. Pero ah\u00ed es donde me parece que es m\u00e1s importante llegar a ese sentido, y una vez que el sentido est\u00e1 jugado, despu\u00e9s es mucho m\u00e1s f\u00e1cil organizar las decisiones para obtener ese sentido. Y el sentido es una cuesti\u00f3n, en general, de estructura dram\u00e1tica. Es decir: ac\u00e1 hay un conflicto, esta escena tiene este conflicto, esto es lo que est\u00e1 en juego en esta escena, ac\u00e1 est\u00e1n los ejes, ac\u00e1 est\u00e1n los puntos de giro de la escena, ac\u00e1 es donde cambia el poder, va para un lado, va para el otro, ac\u00e1 es donde cambia la situaci\u00f3n\u2026 y as\u00ed se resuelve. Y lo que hay que conseguir es potenciar eso. Entonces el mejor ejercicio es editar, me parece. Editar cualquier cosa.&nbsp;<\/p>\n\n\n\n<p>Un ejercicio heredado de Miguel es un ejercicio m\u00e1s pl\u00e1stico, que es agarrar una obra de arte \u2014una obra pl\u00e1stica\u2014 y hacer un <em>clip <\/em>cortando y pegando, y con una m\u00fasica, y entonces integrar todo eso en una especie de ejercicio de sensibilidad pl\u00e1stica para entender las cuestiones del encuadre, de c\u00f3mo los cortes tienen que ver con una sensibilidad pl\u00e1stica, con un criterio de reconocimiento de <em>gestalts<\/em>, pl\u00e1sticas, de cada cuadro, c\u00f3mo cada fotograma te propone una <em>gestalt<\/em>, y c\u00f3mo para entender el corte ten\u00e9s que haber tenido una cierta educaci\u00f3n gest\u00e1ltica de percepci\u00f3n visual \u2014una cosa medio de Rudolf Arnheim, de qu\u00e9 significan las masas, los m\u00e1rgenes, los espacios vac\u00edos, los espacios negativos, las compensaciones, los encuadres, y todo eso lo pon\u00e9s en juego tambi\u00e9n. Es realmente multidisciplinario el montaje. Porque adem\u00e1s de eso tambi\u00e9n les ten\u00e9s que transmitir cuestiones elementales de m\u00fasica: estructuras de comp\u00e1s, c\u00edrculo de quintas, tonalidades lejanas, tonalidades cercanas, aprovechar y agarrar para que puedan entender el concepto de tensi\u00f3n y distensi\u00f3n, que es fundamental, y el concepto de resoluci\u00f3n, de irte de viaje con una tonalidad para volver a tu t\u00f3nica\u2026 cosas que me parece que son absolutamente fundamentales para poder entender todo lo que se te abre cuando decidiste editar.&nbsp;<\/p>\n\n\n\n<p><strong>MP: Me qued\u00e9 pensando en esto que dec\u00edas antes de encarar la devoluci\u00f3n por el lado de la experiencia de visionado de cada alumne, y en relaci\u00f3n a eso me preguntaba si tambi\u00e9n les das pel\u00edculas para ver.<\/strong><\/p>\n\n\n\n<p>ACP: No, esa es una falla. Les muestro, obviamente, en clase, ejemplos de escenas, generalmente cl\u00e1sicas: <em>El padrino<\/em>, <em>Casino<\/em>, mucho [Martin] Scorsese, para justamente mostrar lo que es un montaje mucho m\u00e1s loco. Tambi\u00e9n [Sam] Peckinpah. Yendo m\u00e1s a lo cl\u00e1sico: Lumet, <em>12 hombres en pugna<\/em>\u2026 Es decir, vamos recorriendo un poco c\u00f3mo fueron cambiando los criterios en funci\u00f3n de las \u00e9pocas. Tambi\u00e9n uso much\u00edsimo [David] Fincher, que en <em>Red social,<\/em> por ejemplo, tiene un montaje maravilloso. Y de alguna manera lo que les digo es: a ver, esto es lo que me gusta a m\u00ed. Tr\u00e1iganme ustedes secuencias que les hayan gustado, en todo caso, y las desculamos. Y hagan ese laburo. Es decir: yo les muestro un poco lo que hago yo, o de d\u00f3nde aprend\u00ed yo. Pero la \u00fanica forma en que ustedes pueden terminar de entender esto es agarrando secuencias y viendo los cortes. Yo les muestro c\u00f3mo ver un corte. Agarrar una secuencia, vamos cuadro a cuadro, y vemos d\u00f3nde se cort\u00f3, y por qu\u00e9, y tratamos de inferir el por qu\u00e9 de ciertas decisiones. Porque acordate de que no tenemos el crudo. Nunca ten\u00e9s el crudo. Entonces hay ciertas decisiones que no las pod\u00e9s terminar de adivinar, porque no sab\u00e9s qu\u00e9 estaba del otro lado de la puerta. La puerta se cerr\u00f3 en el \u00faltimo fotograma. Y la puerta se abri\u00f3 en el primer fotograma siguiente. Entonces no lo pod\u00e9s saber a ciencia cierta. Pero s\u00ed, es obvio que hay que mirar mucho. Y lo que no he conseguido hasta ahora \u2014no me ha ido tan bien\u2014 es que yo les propongo: \u201cChe, miren una secuencia, o d\u00edganme qu\u00e9 secuencia, y la analizamos\u201d, y se ve que no estoy muy convencido de lo que digo, porque en l\u00edneas generales esa propuesta ha fracasado. No he conseguido en general que los chicos y las chicas traigan una secuencia de algo que les haya gustado, y que la podamos analizar. Pero por lo menos est\u00e1 planteado el camino, que tiene que ver con mirar los cl\u00e1sicos, como se hizo siempre: mirar lo que est\u00e1 bien y analizarlo. Yo, la primera vez que tuve un Avid, desde un VHS me sub\u00ed la secuencia del tiroteo inicial de <em>La pandilla infernal<\/em>, de <em>The Wild Bunch<\/em>, y me la estudi\u00e9 corte a corte. No llegu\u00e9 a grandes conclusiones, pero la estudi\u00e9. No pude enunciar qu\u00e9 estaba pasando en cada corte, no tuve la capacidad de decir: \u201cbueno, lo que estamos viendo ac\u00e1 es un cl\u00e1sico corte <em>\u00e0 la<\/em> <em>merlonsha <\/em>utilizado en tal y tal\u201d. No pude enciclopedizar eso. Pero a los veinticuatro a\u00f1os yo hab\u00eda visto todos los cortes de la secuencia de Peckinpah. Eso no puede no dejar una huella en una mente \u00e1vida de entender por qu\u00e9 est\u00e1n tom\u00e1ndose las decisiones que se est\u00e1n tomando.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"422\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_00.01.50.361-1024x422.jpg\" alt=\"\" data-id=\"3210\" data-full-url=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_00.01.50.361.jpg\" data-link=\"https:\/\/taipeirevista.com\/?attachment_id=3210\" class=\"wp-image-3210\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_00.01.50.361-1024x422.jpg 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_00.01.50.361-300x124.jpg 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_00.01.50.361-768x317.jpg 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_00.01.50.361-1536x634.jpg 1536w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_00.01.50.361.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"422\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_00.01.47.775-1024x422.jpg\" alt=\"\" data-id=\"3209\" data-full-url=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_00.01.47.775.jpg\" data-link=\"https:\/\/taipeirevista.com\/?attachment_id=3209\" class=\"wp-image-3209\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_00.01.47.775-1024x422.jpg 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_00.01.47.775-300x124.jpg 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_00.01.47.775-768x317.jpg 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_00.01.47.775-1536x634.jpg 1536w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/The.Wild_.Bunch_.1969.1080p.BluRay.x265-RARBG.mp4_snapshot_00.01.47.775.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><figcaption class=\"blocks-gallery-caption\"><em>The Wild Bunch<\/em><\/figcaption><\/figure>\n\n\n\n<p>Dicen que [Orson] Welles aprendi\u00f3 montaje encerr\u00e1ndose tres semanas mirando pel\u00edculas. Es decir: un buen d\u00eda dijo \u201cyo tengo que entender c\u00f3mo es esto del cine\u201d, y se encerr\u00f3, y se puso a ver pel\u00edculas hasta que\u2026 Porque \u00e9l ven\u00eda del teatro, entonces es lo mismo. El d\u00eda que te propon\u00e9s, simplemente te sent\u00e1s y\u2026 claro, a Welles la RKO le alquil\u00f3 una moviola y le dio todas las copias. Pero ahora eso lo puede hacer cualquier persona baj\u00e1ndose una cosa de YouTube. Est\u00e1 al alcance de cualquiera que lo quiera hacer, que tenga las ganas de hacerlo. Yo [con mis trabajos] lo hice varias veces, lo sigo haciendo. La macana es que a m\u00ed me cuesta mucho, y cada vez es m\u00e1s dif\u00edcil llevarte crudo de los proyectos en los que est\u00e1s trabajando para ense\u00f1arle a los alumnos y las alumnas. Porque con todo esto del <em>non disclosure agreements<\/em>, con la corporizaci\u00f3n de los contenidos, es cada vez m\u00e1s dif\u00edcil acceder a que te dejen llevarte material crudo de los proyectos en los que est\u00e1s. Y eso es lo m\u00e1s interesante, porque no vas a producir vos tu propio material crudo. Yo me acuerdo cuando Miguel hab\u00eda producido unas cosas con video para darnos para hacer ejercicio, y no es lo mismo; no es lo mismo editar un material casero filmado en una plaza con una camarita, a editar material de estudio, con actores. Vos sab\u00e9s que el material de estudio est\u00e1 perfecto, entonces pod\u00e9s concentrarte en el montaje. No le vas a echar la culpa a que justo la c\u00e1mara en ese momento la pate\u00f3 el que estaba filmando y entonces no pod\u00e9s hacer el corte ah\u00ed. Para m\u00ed una de las cosas m\u00e1s dif\u00edciles ahora es conseguir crudo para entrenar.<\/p>\n\n\n\n<p><strong>MP: Volviendo un poco a lo que dec\u00edas de esto que hac\u00edas a los veinte a\u00f1os de ver los planos uno por uno, los cortes, \u00bfpens\u00e1s que la mirada que construiste como espectador incidi\u00f3 en tu labor como docente de montaje?<\/strong><\/p>\n\n\n\n<p>ACP: Obvio, uno ense\u00f1a lo que entiende. As\u00ed de corta. Y uno entiende lo que le gusta. O, lo que a uno le gusta. Es un c\u00edrculo: a uno le gusta lo que uno entiende, y uno entiende lo que le gusta. Es un poco as\u00ed. Hay montajes que yo no podr\u00eda explicar porque no los entiendo, porque no me permiten anclar lo que yo s\u00e9 en un objeto del cual yo pueda obtener conocimiento transmisible. Porque uno busca objetos que pertenezcan a la esfera de lo que uno puede transmitir, de lo que uno puede opinar. Uno es selectivo. Uno edita las cosas que van a confirmar aquellas ideas que uno tiene. Ser\u00eda muy arriesgado, y podr\u00eda ser contraproducente, llevar objetos que no pertenecen al \u00e1rea de lo que vos pod\u00e9s hablar. En todo caso, eso te lo pueden hacer \u2014y eso lo hacen\u2014 las alumnas y los alumnos: \u201c\u00bfy tal cosa, la viste?\u201d, \u201cs\u00ed\u201d, \u201c\u00bfy qu\u00e9 opin\u00e1s de eso?\u201d. Y te lo dicen con malicia, porque obviamente no hay nada m\u00e1s divertido que ver patinar a alguien de la generaci\u00f3n anterior porque te demuestra que no todas las respuestas est\u00e1n ah\u00ed (risas). Parte del truco es producir esa erosi\u00f3n. Y es muy dif\u00edcil bajarte del pedestal de seguridad que te da trabajar sobre cosas que sab\u00e9s. Porque es muy dif\u00edcil enfrentarte a las alumnas y los alumnos en un momento donde est\u00e1 tan horizontalizada la relaci\u00f3n social. Es muy dif\u00edcil plantarte ah\u00ed como docente sin tener una cierta seguridad de que vos realmente pod\u00e9s estar ah\u00ed ense\u00f1ando. Cualquier elemento que vulnere esa seguridad, pod\u00e9s sentir que te pone en juego, y te pone, y pone en riesgo tu posici\u00f3n frente a las alumnas y los alumnos. Es todo un desaf\u00edo eso. Yo creo que igual uno se tiene que animar; en la medida en que uno es honesto, y honesta, y en la medida en que uno sabe que, aunque no conozca todo, conoce lo suficiente para estar ah\u00ed \u2014tambi\u00e9n depende de cada grupo, de qu\u00e9 ten\u00e9s adelante\u2014, yo creo que uno puede perfectamente mostrar la hilacha, y no pasa nada. Yo cuando era alumno tambi\u00e9n quer\u00eda que nadie de los que ten\u00eda adelante bajara de [Francis Ford] Coppola. Ten\u00edan que ser Coppola, [Ingmar] Bergman\u2026 genios. Yo no merec\u00eda menos que una genialidad ense\u00f1\u00e1ndome cine (risas), porque el aula es as\u00ed, qu\u00e9 s\u00e9 yo.<\/p>\n\n\n\n<p>Igual uno nunca tiene esa posici\u00f3n, entonces todo es m\u00e1s f\u00e1cil. Pero s\u00ed, uno trae al juego las cosas que lo conmovieron como espectador y con las cuales puede dar cuenta de los fen\u00f3menos que quiere describir, y tambi\u00e9n uno se va dando cuenta c\u00f3mo, inexorablemente, va quedando cada vez m\u00e1s lejos de las nuevas generaciones, de esos lenguajes. Porque cada generaci\u00f3n necesita un nuevo lenguaje que la distinga de la generaci\u00f3n anterior, y que le d\u00e9 identidad, y eso solo se consigue destruyendo y yendo en contra de los lenguajes previos. A medida que van pasando los a\u00f1os \u2014yo ya tengo cuarenta y ocho&#8230; El otro d\u00eda habl\u00e1bamos de que la generaci\u00f3n de los <em>floggers<\/em> y de los <em>emos<\/em> \u00a1es una generaci\u00f3n del pasado! Yo puedo recordar perfectamente la \u00e9poca en que yo ve\u00eda a los <em>floggers <\/em>y a los <em>emos<\/em> como un fen\u00f3meno absolutamente novedoso y emergente, \u00a1y ya es prehistoria! Es decir que ya pasaron olas y olas de lenguajes, de estructuras, de identificaciones, y yo creo que un poco la ventaja de lo cl\u00e1sico, la ventaja de aferrarte a lo cl\u00e1sico, es que es aquello que te permite seguir en contacto con las siguientes generaciones. Es el \u00faltimo gir\u00f3n de verdad que trasciende las oleadas generacionales, y es un lugar donde te pod\u00e9s encontrar con gente que est\u00e1 empezando\u2026 pod\u00e9s encontrarte con un <em>centennial<\/em> a hablar de c\u00f3mo cort\u00f3 Lumet <em>12 hombres en pugna <\/em>y por qu\u00e9, y no est\u00e1s hablando de huevadas. Entonces creo que la apuesta a lo cl\u00e1sico es tambi\u00e9n una apuesta a no quedar desautorizado, s\u00ed, pero [tambi\u00e9n] a no perder vigencia.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"613\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.31.13.907-1024x613.jpg\" alt=\"\" data-id=\"3211\" data-full-url=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.31.13.907.jpg\" data-link=\"https:\/\/taipeirevista.com\/?attachment_id=3211\" class=\"wp-image-3211\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.31.13.907-1024x613.jpg 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.31.13.907-300x179.jpg 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.31.13.907-768x459.jpg 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.31.13.907-1536x919.jpg 1536w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.31.13.907.jpg 1792w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"613\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.32.04.995-1024x613.jpg\" alt=\"\" data-id=\"3212\" data-full-url=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.32.04.995.jpg\" data-link=\"https:\/\/taipeirevista.com\/?attachment_id=3212\" class=\"wp-image-3212\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.32.04.995-1024x613.jpg 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.32.04.995-300x179.jpg 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.32.04.995-768x459.jpg 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.32.04.995-1536x919.jpg 1536w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.32.04.995.jpg 1792w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"613\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.32.14.260-1024x613.jpg\" alt=\"\" data-id=\"3213\" data-full-url=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.32.14.260.jpg\" data-link=\"https:\/\/taipeirevista.com\/?attachment_id=3213\" class=\"wp-image-3213\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.32.14.260-1024x613.jpg 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.32.14.260-300x179.jpg 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.32.14.260-768x459.jpg 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.32.14.260-1536x919.jpg 1536w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.32.14.260.jpg 1792w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"613\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.32.24.640-1024x613.jpg\" alt=\"\" data-id=\"3214\" data-full-url=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.32.24.640.jpg\" data-link=\"https:\/\/taipeirevista.com\/?attachment_id=3214\" class=\"wp-image-3214\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.32.24.640-1024x613.jpg 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.32.24.640-300x179.jpg 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.32.24.640-768x459.jpg 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.32.24.640-1536x919.jpg 1536w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/12.Angry_.Men_.1957.1080p.BluRay.x264-YTS.AM_.mp4_snapshot_01.32.24.640.jpg 1792w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><figcaption class=\"blocks-gallery-caption\"><em>12 Angry Men<\/em> (Sidney Lumet, 1957)<\/figcaption><\/figure>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-small-font-size\"><strong>Notas:<\/strong><\/p>\n\n\n\n<p class=\"has-small-font-size\" id=\"nota1\"><strong>1<\/strong> La ENERC (Escuela Nacional de Experimentaci\u00f3n y Realizaci\u00f3n Cinematogr\u00e1fica) es una instituci\u00f3n p\u00fablica y estatal argentina, dispuesta por la Ley de Cinematograf\u00eda de 1957 y fundada en 1965. [N. de los E.]<\/p>\n\n\n\n<p class=\"has-small-font-size\" id=\"nota2\"><strong>2<\/strong> FUC es la Fundaci\u00f3n Universidad del Cine, instituci\u00f3n privada situada en Buenos Aires y fundada en 1991 por el cineasta Manuel Antin. [N. de los E.]<\/p>\n\n\n\n<p class=\"has-small-font-size\" id=\"nota3\"><strong>3<\/strong> Ver\u00f3nica Cura es docente y productora cinematogr\u00e1fica. Ha dictado clases en ENERC, EICTV y UNTREF, y producido films como<em> Whisky Romeo Zul\u00fa<\/em> (Enrique Pi\u00f1eyro, 2004), <em>El otro<\/em> (Ariel Rotter, 2007), <em>La mujer sin cabeza<\/em> (Lucrecia Martel, 2008) y <em>Las acacias<\/em> (Pablo Giorgelli, 2010). Desde 2008 posee su propia compa\u00f1\u00eda de producci\u00f3n, Ut\u00f3pica Cine. [N. de los E.]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando estaba estudiando cine yo no quer\u00eda ser docente de cine, quer\u00eda ser cineasta. Y, para m\u00ed, hab\u00eda una clara distinci\u00f3n entre los docentes de cine y los cineastas. Los docentes de cine no eran cineastas. Era raro: hab\u00eda claramente docentes de cine cineastas, pero no eran la mayor\u00eda. La mayor\u00eda de los docentes de cine ten\u00edan trabajo porque normalmente vos acced\u00edas a la docencia cinematogr\u00e1fica a trav\u00e9s de un curr\u00edculum profesional, que eso es lo que te daba a vos la certeza de que la persona que estaba ah\u00ed ten\u00eda cierta autoridad para impartir una materia. (&#8230;) Ahora empieza a cambiar ese paradigma, y empieza a aparecer esta cuesti\u00f3n de la docencia cinematogr\u00e1fica casi como una cuesti\u00f3n espec\u00edfica(&#8230;)<\/p>\n","protected":false},"author":23,"featured_media":4270,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[56],"tags":[438,417,58,81,82,415,500,439,440,151,118],"class_list":{"0":"post-3206","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-educacion","8":"tag-alejandro-penovi","9":"tag-archivo-docente","10":"tag-cine-argentino","11":"tag-docencia","12":"tag-educacion","13":"tag-enerc","14":"tag-ensenanza-del-montaje","15":"tag-fuc","16":"tag-miguel-perez","17":"tag-sam-peckinpah","18":"tag-sidney-lumet"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los criterios constructivos. Entrevista a Alejandro Carrillo Penovi, docente de montaje - TAIPEI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/taipeirevista.com\/index.php\/2021\/07\/14\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los criterios constructivos. Entrevista a Alejandro Carrillo Penovi, docente de montaje - TAIPEI\" \/>\n<meta property=\"og:description\" content=\"Cuando estaba estudiando cine yo no quer\u00eda ser docente de cine, quer\u00eda ser cineasta. Y, para m\u00ed, hab\u00eda una clara distinci\u00f3n entre los docentes de cine y los cineastas. Los docentes de cine no eran cineastas. Era raro: hab\u00eda claramente docentes de cine cineastas, pero no eran la mayor\u00eda. La mayor\u00eda de los docentes de cine ten\u00edan trabajo porque normalmente vos acced\u00edas a la docencia cinematogr\u00e1fica a trav\u00e9s de un curr\u00edculum profesional, que eso es lo que te daba a vos la certeza de que la persona que estaba ah\u00ed ten\u00eda cierta autoridad para impartir una materia. (...) Ahora empieza a cambiar ese paradigma, y empieza a aparecer esta cuesti\u00f3n de la docencia cinematogr\u00e1fica casi como una cuesti\u00f3n espec\u00edfica(...)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/taipeirevista.com\/index.php\/2021\/07\/14\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\/\" \/>\n<meta property=\"og:site_name\" content=\"TAIPEI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revistataipei\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-14T22:53:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-18T14:27:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/penovi-editado-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Iv\u00e1n Bustinduy | Milagros Porta\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@taipeicritica\" \/>\n<meta name=\"twitter:site\" content=\"@taipeicritica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Iv\u00e1n Bustinduy | Milagros Porta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"36 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2021\\\/07\\\/14\\\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2021\\\/07\\\/14\\\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\\\/\"},\"author\":{\"name\":\"Iv\u00e1n Bustinduy | Milagros Porta\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#\\\/schema\\\/person\\\/7fae9e175c0cea668fa9d614bd43547f\"},\"headline\":\"Los criterios constructivos. Entrevista a Alejandro Carrillo Penovi, docente de montaje\",\"datePublished\":\"2021-07-14T22:53:02+00:00\",\"dateModified\":\"2021-12-18T14:27:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2021\\\/07\\\/14\\\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\\\/\"},\"wordCount\":7209,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2021\\\/07\\\/14\\\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/taipeirevista.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/penovi-editado-1.png\",\"keywords\":[\"Alejandro Penovi\",\"Archivo docente\",\"Cine argentino\",\"Docencia\",\"Educaci\u00f3n\",\"ENERC\",\"Ense\u00f1anza del montaje\",\"FUC\",\"Miguel P\u00e9rez\",\"Sam Peckinpah\",\"Sidney Lumet\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2021\\\/07\\\/14\\\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2021\\\/07\\\/14\\\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\\\/\",\"url\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2021\\\/07\\\/14\\\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\\\/\",\"name\":\"Los criterios constructivos. Entrevista a Alejandro Carrillo Penovi, docente de montaje - TAIPEI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2021\\\/07\\\/14\\\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2021\\\/07\\\/14\\\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/taipeirevista.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/penovi-editado-1.png\",\"datePublished\":\"2021-07-14T22:53:02+00:00\",\"dateModified\":\"2021-12-18T14:27:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2021\\\/07\\\/14\\\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2021\\\/07\\\/14\\\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2021\\\/07\\\/14\\\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\\\/#primaryimage\",\"url\":\"https:\\\/\\\/taipeirevista.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/penovi-editado-1.png\",\"contentUrl\":\"https:\\\/\\\/taipeirevista.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/penovi-editado-1.png\",\"width\":768,\"height\":470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2021\\\/07\\\/14\\\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/taipeirevista.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los criterios constructivos. Entrevista a Alejandro Carrillo Penovi, docente de montaje\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#website\",\"url\":\"https:\\\/\\\/taipeirevista.com\\\/\",\"name\":\"TAIPEI\",\"description\":\"Cr\u00edtica de cine\",\"publisher\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/taipeirevista.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#organization\",\"name\":\"Taipei \\\/ Cr\u00edtica de cine\",\"url\":\"https:\\\/\\\/taipeirevista.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/taipeirevista.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/TAIPEI-LOGO-1.1-SIN-GRIS.png\",\"contentUrl\":\"https:\\\/\\\/taipeirevista.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/TAIPEI-LOGO-1.1-SIN-GRIS.png\",\"width\":599,\"height\":599,\"caption\":\"Taipei \\\/ Cr\u00edtica de cine\"},\"image\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/revistataipei\",\"https:\\\/\\\/x.com\\\/taipeicritica\",\"https:\\\/\\\/www.instagram.com\\\/taipeicritica\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#\\\/schema\\\/person\\\/7fae9e175c0cea668fa9d614bd43547f\",\"name\":\"Iv\u00e1n Bustinduy | Milagros Porta\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b7f26be13a627ab5b0b37fac125911b2c819ff3f6d0f91c805b2af12e0852a09?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b7f26be13a627ab5b0b37fac125911b2c819ff3f6d0f91c805b2af12e0852a09?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b7f26be13a627ab5b0b37fac125911b2c819ff3f6d0f91c805b2af12e0852a09?s=96&d=mm&r=g\",\"caption\":\"Iv\u00e1n Bustinduy | Milagros Porta\"},\"description\":\"Iv\u00e1n Bustinduy naci\u00f3 en Buenos Aires en 1997. Se form\u00f3 como realizador cinematogr\u00e1fico y como profesor en la Universidad del Cine (FUC), donde actualmente se desempe\u00f1a como docente en la asignatura Direcci\u00f3n I. Es parte del Colectivo Rutemberg, espacio en el cual trabaja como coordinador de producci\u00f3n y director. Dirigi\u00f3 los cortometrajes Empanadas y El segundo hombre. Se desempe\u00f1a como coordinador en Taipei, donde escribe sobre cine y educaci\u00f3n. Acaba de finalizar su cortometraje Carga animal. Contacto: bustinduyivan@gmail.com. Milagros Porta naci\u00f3 en Buenos Aires en 2002. Estudia la Licenciatura en Artes de la Escritura (UNA). Edita y escribe en Taipei. Particip\u00f3 en el Jurado Joven del 36\u00ba Festival de Mar del Plata y en el Jurado de Cortometrajes del 11\u00ba FICIC. En 2022 public\u00f3 el libro de cuentos Aguamala (Hex\u00e1gono Editoras) e integr\u00f3 antolog\u00edas de narradores j\u00f3venes como Los amigos dif\u00edciles (Editorial Nn) y Tan diversa (Bienal de Arte Joven de Buenos Aires, publicada por Mardulce). Contacto: milagrosporta222@gmail.com.\",\"url\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/author\\\/ivanmilagros\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los criterios constructivos. Entrevista a Alejandro Carrillo Penovi, docente de montaje - TAIPEI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/taipeirevista.com\/index.php\/2021\/07\/14\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\/","og_locale":"es_ES","og_type":"article","og_title":"Los criterios constructivos. Entrevista a Alejandro Carrillo Penovi, docente de montaje - TAIPEI","og_description":"Cuando estaba estudiando cine yo no quer\u00eda ser docente de cine, quer\u00eda ser cineasta. Y, para m\u00ed, hab\u00eda una clara distinci\u00f3n entre los docentes de cine y los cineastas. Los docentes de cine no eran cineastas. Era raro: hab\u00eda claramente docentes de cine cineastas, pero no eran la mayor\u00eda. La mayor\u00eda de los docentes de cine ten\u00edan trabajo porque normalmente vos acced\u00edas a la docencia cinematogr\u00e1fica a trav\u00e9s de un curr\u00edculum profesional, que eso es lo que te daba a vos la certeza de que la persona que estaba ah\u00ed ten\u00eda cierta autoridad para impartir una materia. (...) Ahora empieza a cambiar ese paradigma, y empieza a aparecer esta cuesti\u00f3n de la docencia cinematogr\u00e1fica casi como una cuesti\u00f3n espec\u00edfica(...)","og_url":"https:\/\/taipeirevista.com\/index.php\/2021\/07\/14\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\/","og_site_name":"TAIPEI","article_publisher":"https:\/\/www.facebook.com\/revistataipei","article_published_time":"2021-07-14T22:53:02+00:00","article_modified_time":"2021-12-18T14:27:27+00:00","og_image":[{"width":768,"height":470,"url":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/penovi-editado-1.png","type":"image\/png"}],"author":"Iv\u00e1n Bustinduy | Milagros Porta","twitter_card":"summary_large_image","twitter_creator":"@taipeicritica","twitter_site":"@taipeicritica","twitter_misc":{"Escrito por":"Iv\u00e1n Bustinduy | Milagros Porta","Tiempo de lectura":"36 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/taipeirevista.com\/index.php\/2021\/07\/14\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\/#article","isPartOf":{"@id":"https:\/\/taipeirevista.com\/index.php\/2021\/07\/14\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\/"},"author":{"name":"Iv\u00e1n Bustinduy | Milagros Porta","@id":"https:\/\/taipeirevista.com\/#\/schema\/person\/7fae9e175c0cea668fa9d614bd43547f"},"headline":"Los criterios constructivos. Entrevista a Alejandro Carrillo Penovi, docente de montaje","datePublished":"2021-07-14T22:53:02+00:00","dateModified":"2021-12-18T14:27:27+00:00","mainEntityOfPage":{"@id":"https:\/\/taipeirevista.com\/index.php\/2021\/07\/14\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\/"},"wordCount":7209,"commentCount":0,"publisher":{"@id":"https:\/\/taipeirevista.com\/#organization"},"image":{"@id":"https:\/\/taipeirevista.com\/index.php\/2021\/07\/14\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\/#primaryimage"},"thumbnailUrl":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/penovi-editado-1.png","keywords":["Alejandro Penovi","Archivo docente","Cine argentino","Docencia","Educaci\u00f3n","ENERC","Ense\u00f1anza del montaje","FUC","Miguel P\u00e9rez","Sam Peckinpah","Sidney Lumet"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/taipeirevista.com\/index.php\/2021\/07\/14\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/taipeirevista.com\/index.php\/2021\/07\/14\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\/","url":"https:\/\/taipeirevista.com\/index.php\/2021\/07\/14\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\/","name":"Los criterios constructivos. Entrevista a Alejandro Carrillo Penovi, docente de montaje - TAIPEI","isPartOf":{"@id":"https:\/\/taipeirevista.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/taipeirevista.com\/index.php\/2021\/07\/14\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\/#primaryimage"},"image":{"@id":"https:\/\/taipeirevista.com\/index.php\/2021\/07\/14\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\/#primaryimage"},"thumbnailUrl":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/penovi-editado-1.png","datePublished":"2021-07-14T22:53:02+00:00","dateModified":"2021-12-18T14:27:27+00:00","breadcrumb":{"@id":"https:\/\/taipeirevista.com\/index.php\/2021\/07\/14\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/taipeirevista.com\/index.php\/2021\/07\/14\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/taipeirevista.com\/index.php\/2021\/07\/14\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\/#primaryimage","url":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/penovi-editado-1.png","contentUrl":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/penovi-editado-1.png","width":768,"height":470},{"@type":"BreadcrumbList","@id":"https:\/\/taipeirevista.com\/index.php\/2021\/07\/14\/los-criterios-constructivos-entrevista-a-alejandro-penovi-docente-de-montaje\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/taipeirevista.com\/"},{"@type":"ListItem","position":2,"name":"Los criterios constructivos. Entrevista a Alejandro Carrillo Penovi, docente de montaje"}]},{"@type":"WebSite","@id":"https:\/\/taipeirevista.com\/#website","url":"https:\/\/taipeirevista.com\/","name":"TAIPEI","description":"Cr\u00edtica de cine","publisher":{"@id":"https:\/\/taipeirevista.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/taipeirevista.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/taipeirevista.com\/#organization","name":"Taipei \/ Cr\u00edtica de cine","url":"https:\/\/taipeirevista.com\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/taipeirevista.com\/#\/schema\/logo\/image\/","url":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/08\/TAIPEI-LOGO-1.1-SIN-GRIS.png","contentUrl":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/08\/TAIPEI-LOGO-1.1-SIN-GRIS.png","width":599,"height":599,"caption":"Taipei \/ Cr\u00edtica de cine"},"image":{"@id":"https:\/\/taipeirevista.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/revistataipei","https:\/\/x.com\/taipeicritica","https:\/\/www.instagram.com\/taipeicritica\/"]},{"@type":"Person","@id":"https:\/\/taipeirevista.com\/#\/schema\/person\/7fae9e175c0cea668fa9d614bd43547f","name":"Iv\u00e1n Bustinduy | Milagros Porta","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/b7f26be13a627ab5b0b37fac125911b2c819ff3f6d0f91c805b2af12e0852a09?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b7f26be13a627ab5b0b37fac125911b2c819ff3f6d0f91c805b2af12e0852a09?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b7f26be13a627ab5b0b37fac125911b2c819ff3f6d0f91c805b2af12e0852a09?s=96&d=mm&r=g","caption":"Iv\u00e1n Bustinduy | Milagros Porta"},"description":"Iv\u00e1n Bustinduy naci\u00f3 en Buenos Aires en 1997. Se form\u00f3 como realizador cinematogr\u00e1fico y como profesor en la Universidad del Cine (FUC), donde actualmente se desempe\u00f1a como docente en la asignatura Direcci\u00f3n I. Es parte del Colectivo Rutemberg, espacio en el cual trabaja como coordinador de producci\u00f3n y director. Dirigi\u00f3 los cortometrajes Empanadas y El segundo hombre. Se desempe\u00f1a como coordinador en Taipei, donde escribe sobre cine y educaci\u00f3n. Acaba de finalizar su cortometraje Carga animal. Contacto: bustinduyivan@gmail.com. Milagros Porta naci\u00f3 en Buenos Aires en 2002. Estudia la Licenciatura en Artes de la Escritura (UNA). Edita y escribe en Taipei. Particip\u00f3 en el Jurado Joven del 36\u00ba Festival de Mar del Plata y en el Jurado de Cortometrajes del 11\u00ba FICIC. En 2022 public\u00f3 el libro de cuentos Aguamala (Hex\u00e1gono Editoras) e integr\u00f3 antolog\u00edas de narradores j\u00f3venes como Los amigos dif\u00edciles (Editorial Nn) y Tan diversa (Bienal de Arte Joven de Buenos Aires, publicada por Mardulce). Contacto: milagrosporta222@gmail.com.","url":"https:\/\/taipeirevista.com\/index.php\/author\/ivanmilagros\/"}]}},"jetpack_featured_media_url":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2021\/07\/penovi-editado-1.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/posts\/3206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/comments?post=3206"}],"version-history":[{"count":21,"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/posts\/3206\/revisions"}],"predecessor-version":[{"id":6807,"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/posts\/3206\/revisions\/6807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/media\/4270"}],"wp:attachment":[{"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/media?parent=3206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/categories?post=3206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/tags?post=3206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}