{"id":5109,"date":"2022-04-08T12:00:16","date_gmt":"2022-04-08T12:00:16","guid":{"rendered":"https:\/\/taipeirevista.com\/?p=5109"},"modified":"2022-08-09T08:26:38","modified_gmt":"2022-08-09T08:26:38","slug":"la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion","status":"publish","type":"post","link":"https:\/\/taipeirevista.com\/index.php\/2022\/04\/08\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\/","title":{"rendered":"La muerte de Robert McKee. Entrevista a Javier Trigales, docente de guion"},"content":{"rendered":"\n<p><em>Javier Trigales es egresado de la diplomatura de cine de la Escuela TAI. Nacido y establecido en La Coru\u00f1a (Galicia, Espa\u00f1a), ha trabajado como guionista de cine y televisi\u00f3n, <\/em>copywriter <em>en publicidad, periodista cultural, cr\u00edtico y docente de cine. Actualmente, es docente de guion en la universidad CESUGA (Centro de Estudios Superiores Universitarios de Galicia) y se dedica a la gesti\u00f3n cultural, coordinando talleres, cursos, exposiciones y proyecciones de todo tipo en su ciudad natal y alrededores.&nbsp;<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p class=\"has-text-align-right has-text-color has-small-font-size\" style=\"color:#52585d\"><strong>ARCHIVO DOCENTE #6<\/strong><\/p>\n\n\n\n<div style=\"height:17px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Iv\u00e1n Bustinduy: \u00bfC\u00f3mo intercal\u00e1s la gesti\u00f3n cultural y la docencia de cine?<\/strong><\/p>\n\n\n\n<p>Javier Trigales: A trav\u00e9s de los a\u00f1os he dado cursos y seminarios por much\u00edsimos sitios como festivales de cine, tanto en Galicia como por el resto de Espa\u00f1a. Tuve la oportunidad de hacer colaboraciones de lo m\u00e1s variado, cosas muy chulas como colaborar con pianistas y hablar de la m\u00fasica en el cine de Tarkovski o de Terrence Malick. Tambi\u00e9n hago un ciclo en 35mm en verano, donde proyecto cl\u00e1sicos de todo tipo, desde [Jean-Luc] Godard hasta David Lynch, pasando por [Quentin] Tarantino, Agn\u00e8s Varda, lo que se te pueda ocurrir. Es una especie de <em>cineforum<\/em>, porque despu\u00e9s de la proyecci\u00f3n, que es a altas horas de la noche, hacemos un coloquio con alguien del \u00e1mbito de la cultura, que intento que no sea del mundo del cine: m\u00fasicos, arquitectos, core\u00f3grafos, escritores, pintores\u2026 Gente que no tenga un v\u00ednculo concreto con el cine, para intercalar disciplinas. A m\u00ed me interesa much\u00edsimo la opini\u00f3n que pueda tener una poeta sobre una pel\u00edcula de Werner Herzog, o lo que opina un bailar\u00edn del estatismo de [Robert] Bresson. Ese tipo de miradas me resultan muy enriquecedoras respecto a las que podamos tener los que estamos m\u00e1s metidos dentro del asunto, y adem\u00e1s para que [las actividades] no se conviertan en un gueto, donde estemos siempre los mismos hablando de las mismas cosas. No me gustan nada las actividades a las que va siempre gente del mismo grupo. Yo creo que juntar p\u00fablicos, como gestor cultural, es algo muy importante. A la filmoteca va todo tipo de gente, a una exposici\u00f3n de fotograf\u00eda lo mismo, a una obra de teatro lo mismo: yo quiero que esa gente contacte entre ellos y que ah\u00ed pasen cosas. Por eso intento que las cosas que hago siempre partan del cine, para ir luego hacia otros lados.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/javier-trigales-b-n-1024x576.jpg\" alt=\"\" class=\"wp-image-5111\" width=\"579\" height=\"325\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/javier-trigales-b-n-1024x576.jpg 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/javier-trigales-b-n-300x169.jpg 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/javier-trigales-b-n-768x432.jpg 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/javier-trigales-b-n-1536x863.jpg 1536w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/javier-trigales-b-n-2048x1151.jpg 2048w\" sizes=\"(max-width: 579px) 100vw, 579px\" \/><\/figure>\n<\/div>\n\n\n<p><strong>IB: \u00bfY la materia que das en CESUGA, en qu\u00e9 consiste?<\/strong><\/p>\n\n\n\n<p>JT: All\u00ed, los m\u00f3dulos que hay no son precisamente del audiovisual, o por lo menos no de una manera tangencial. Yo estoy dando clases de guion, y me doy cuenta de que el guion, en el fondo, es contar historias. Y contar historias tambi\u00e9n es contar una idea. As\u00ed que lo que yo cuento para escribir un guion se puede adaptar tranquilamente a cualquier tipo de proyecto y a cualquier tipo de trabajo. Es poner en orden tus pensamientos, expresarlos de una manera clara y concisa, hacer unos puntos de giro, hacer unas subidas y bajadas, jugar con el receptor de la historia que est\u00e1s contando.&nbsp;<\/p>\n\n\n\n<p>Es una experiencia que est\u00e1 siendo bastante gratificante, porque adem\u00e1s es gente que no tiene pr\u00e1cticamente ninguna noci\u00f3n de historia audiovisual, as\u00ed que en el fondo les da igual que les hable de <em>El juego del calamar <\/em>como que les hable de [Jean-Luc] Godard. Eso es muy curioso, porque te das cuenta que reaccionan igual de bien. Parece que tenemos interiorizado que necesitamos un aprendizaje previo, que para llegar a gente como [Kenji] Mizoguchi, Mikio Naruse, [Yasujiro] Ozu o, no lo s\u00e9, Chantal Akerman, hay que seguir toda una fase: empezar con el cine comercial, luego, poco a poco, meterse en otros tipos de cine. Aqu\u00ed no, lo hacemos a machete. Les pongo piezas lo m\u00e1s variadas posibles, sin ning\u00fan tipo de problema por su parte, y reaccionan igual de bien al \u00faltimo videoclip de Beyonc\u00e9 que a un cortometraje de [Artavazd] Pelechian. Eso me parece muy sorprendente. Hablamos siempre pestes de esta generaci\u00f3n, de que est\u00e1 con los m\u00f3viles, de que est\u00e1 con las plataformas digitales, solo Netflix y dem\u00e1s\u2026 A lo mejor es porque simplemente no se les ofrece otra cosa. La verdad es que la experiencia que estoy teniendo es muy buena.&nbsp;<\/p>\n\n\n\n<p><strong>IB: De hecho, es lo que propone [Jonathan] Rosenbaum en <\/strong><strong><em>Las guerras del cine<\/em><\/strong><strong>: que la concepci\u00f3n que tenemos de los espectadores de cine es siempre una profec\u00eda de autocumplimiento que el mercado necesita para seguir bajando sus contenidos.&nbsp;<\/strong><\/p>\n\n\n\n<p>JT: Claro. Es una especie de falsa alarma cultural, la que nos dice que el p\u00fablico demanda ciertas cosas. No, el p\u00fablico es mayor de edad, y cuando yo era quincea\u00f1ero pues ten\u00eda un acceso a pel\u00edculas en la televisi\u00f3n que ahora ya no existe. No era solo yo, mis compa\u00f1eros las ve\u00edan igualmente. En ese sentido, aparte de Rosenbaum, yo tuve mucho en cuenta tambi\u00e9n este peque\u00f1o gran libro de Alain Bergala, <em>La hip\u00f3tesis del cine<\/em>. Aqu\u00ed en Galicia, adem\u00e1s, se est\u00e1n haciendo una serie de propuestas educativas en las que se les pone a los ni\u00f1os de ocho a diez a\u00f1os pel\u00edculas de Akerman, de Jonas Mekas y dem\u00e1s, para que luego las reinterpreten y hagan sus versiones. Ver las peque\u00f1as piezas de ni\u00f1os de nueve a\u00f1os, influidos por el cine de Mekas, es una pasada. Muchas veces somos nosotros los que nos autoimponemos lo que pueden o no pueden estar dispuestos a entender o consumir nuestros alumnos como espectadores.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"5117\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Beyonce-JAY-Z-Childish-Gambino-Oumou-Sangare-\u2013-MOOD-4-EVA-Official-Video-1080p_24fps_H264-128kbit_AAC.mp4_snapshot_04.39.479-1024x576.png\" alt=\"\" class=\"wp-image-5117\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Beyonce-JAY-Z-Childish-Gambino-Oumou-Sangare-\u2013-MOOD-4-EVA-Official-Video-1080p_24fps_H264-128kbit_AAC.mp4_snapshot_04.39.479-1024x576.png 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Beyonce-JAY-Z-Childish-Gambino-Oumou-Sangare-\u2013-MOOD-4-EVA-Official-Video-1080p_24fps_H264-128kbit_AAC.mp4_snapshot_04.39.479-300x169.png 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Beyonce-JAY-Z-Childish-Gambino-Oumou-Sangare-\u2013-MOOD-4-EVA-Official-Video-1080p_24fps_H264-128kbit_AAC.mp4_snapshot_04.39.479-768x432.png 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Beyonce-JAY-Z-Childish-Gambino-Oumou-Sangare-\u2013-MOOD-4-EVA-Official-Video-1080p_24fps_H264-128kbit_AAC.mp4_snapshot_04.39.479-1536x864.png 1536w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Beyonce-JAY-Z-Childish-Gambino-Oumou-Sangare-\u2013-MOOD-4-EVA-Official-Video-1080p_24fps_H264-128kbit_AAC.mp4_snapshot_04.39.479.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"5118\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Beyonce-JAY-Z-Childish-Gambino-Oumou-Sangare-\u2013-MOOD-4-EVA-Official-Video-1080p_24fps_H264-128kbit_AAC.mp4_snapshot_05.11.760-1024x576.png\" alt=\"\" class=\"wp-image-5118\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Beyonce-JAY-Z-Childish-Gambino-Oumou-Sangare-\u2013-MOOD-4-EVA-Official-Video-1080p_24fps_H264-128kbit_AAC.mp4_snapshot_05.11.760-1024x576.png 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Beyonce-JAY-Z-Childish-Gambino-Oumou-Sangare-\u2013-MOOD-4-EVA-Official-Video-1080p_24fps_H264-128kbit_AAC.mp4_snapshot_05.11.760-300x169.png 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Beyonce-JAY-Z-Childish-Gambino-Oumou-Sangare-\u2013-MOOD-4-EVA-Official-Video-1080p_24fps_H264-128kbit_AAC.mp4_snapshot_05.11.760-768x432.png 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Beyonce-JAY-Z-Childish-Gambino-Oumou-Sangare-\u2013-MOOD-4-EVA-Official-Video-1080p_24fps_H264-128kbit_AAC.mp4_snapshot_05.11.760-1536x864.png 1536w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Beyonce-JAY-Z-Childish-Gambino-Oumou-Sangare-\u2013-MOOD-4-EVA-Official-Video-1080p_24fps_H264-128kbit_AAC.mp4_snapshot_05.11.760.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<figcaption class=\"blocks-gallery-caption\">Beyonc\u00e9, JAY-Z, Childish Gambino y Oumou Sangar\u00e9, &#8220;Mood 4 Eva&#8221; (2020)<\/figcaption><\/figure>\n\n\n\n<div style=\"height:11px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>IB: En ese sentido, hay algo de <em>acercar <\/em>que es muy de Bergala, de ofrecer una alternativa, desde un lugar no prejuicioso. Es decir, no desde el lugar de \u201cesto que trajiste no es verdadero, por m\u00e1s que sea lo \u00fanico que tuviste a mano. Est\u00e1 mal. Tom\u00e1 esto, que es la verdad\u201d.<\/strong><\/p>\n\n\n\n<p>JT: Yo eso lo combato much\u00edsimo, tanto desde el cine de autor como desde el <em>mainstream<\/em>. Yo para nada rechazo el <em>mainstream<\/em>, soy amante del buen <em>mainstream<\/em>, de las buenas pel\u00edculas hechas dentro de la industria. Siempre digo que hay dos tipos de pel\u00edculas, las buenas y las malas. El resto de las clasificaciones me dan bastante igual. No entiendo a la gente que dice \u201cme gusta este tipo de cine\u201d. No puede ser. Si te gusta el cine de verdad tienes que ser omn\u00edvoro, no puedes ponerte l\u00edmites de \u201ceste tipo de cine s\u00ed, y esta nacionalidad s\u00ed\u201d, o \u201ceste independiente s\u00ed, pero este <em>underground<\/em> no\u201d. Tienes que tener un cierto tipo de inter\u00e9s y de curiosidad por el cine, que te permita hacer t\u00fa mismo una especie de selecci\u00f3n, una curadur\u00eda. Yo veo dos o tres pel\u00edculas al d\u00eda, cuando puedo, y siempre me imagino que estoy haciendo un ciclo, un festival en miniatura para m\u00ed mismo. Todos los d\u00edas comisar\u00edo ese festival y elijo la secci\u00f3n, algo que me provoca un placer inmenso. Yo creo que la gente deber\u00eda hacer algo parecido en sus casas. La curiosidad me parece important\u00ecsima, y no solo con respecto al cine, ya que el cine es un arte-esponja \u2014se nutre de much\u00edsimas otras cosas, como la literatura, la m\u00fasica, el ensayo, la filosof\u00eda, el teatro, la \u00f3pera, la vida, el salir de fiesta\u2026 Todo acaba teniendo una resonancia en tu trabajo en el audiovisual.<\/p>\n\n\n\n<p><strong>IB: Es darle al estudiante la posibilidad de hacer esa selecci\u00f3n a partir de sus intereses. Intereses que muchas veces son simplemente sensaciones, intuiciones, algo menos racional. Ayudarlos a que se puedan tirar a la pileta, a ver qu\u00e9 pasa.<\/strong><\/p>\n\n\n\n<p>JT: S\u00ed, yo siempre intento potenciar lo que ellos dicen y alentarlos a que sigan investigando. Nunca se me ocurrir\u00eda decirles que <em>El juego del calamar <\/em>es una mierda, o que no vean Netflix y que vean otras plataformas de cine de autor. Si ven una pel\u00edcula en concreto, si vienen con que han visto la \u00faltima pel\u00edcula de Marvel, intento hablar un poco con ellos sobre esa pel\u00edcula, si realmente les ha gustado y por qu\u00e9. A lo mejor, desde ese \u201cpor qu\u00e9\u201d encuentras un peque\u00f1o hilo que te ayuda para llevarlos a sitios m\u00e1s f\u00e9rtiles que el del cine de superh\u00e9roes. No est\u00e1 mal que vean cine de superh\u00e9roes, pero est\u00e1 bueno que sepan que, aparte, hay cosas que conectan con otros lados. Yo doy clase tambi\u00e9n en una escuela de cine que se llama Educa tu Mirada, que est\u00e1 en Barcelona, donde formo parte del profesorado con un curso sobre cine experimental y de autor. Ah\u00ed doy una clase que llamo \u201cEl hilo invisible: del cine <em>mainstream<\/em> al cine de autor\u201d. Lo que hago es eso, precisamente: ni defenestrar el <em>mainstream<\/em> ni ponderar el cine de autor como el \u00fanico posible o v\u00e1lido dentro de nuestro trabajo. Las conexiones son much\u00edsimas m\u00e1s que las que nos podemos imaginar, o por lo menos es lo que yo creo. No pienso que haya que hacer una especie de bandos enfrentados, sino que creo que el di\u00e1logo puede ser muy productivo.&nbsp;<\/p>\n\n\n\n<p><strong>IB: Creo que eso es casi contracultural, en el sentido de que el mercado funciona as\u00ed. Es com\u00fan hablar con productores (por m\u00e1s que uno tenga claro que los bandos son una mentira, una antinomia que nada m\u00e1s le sirve a los cines menos interesantes o desafiantes para encontrar su rinc\u00f3n) y que te quieran encasillar permanentemente de \u201cdirector de <\/strong><strong><em>mainstream<\/em><\/strong><strong>\u201d o de \u201cdirector de cine de festivales\u201d. Hacer cine con una voluntad popular parece equivalente a hacer basura, y eso no es cierto.&nbsp;<\/strong><\/p>\n\n\n\n<p>JT: Luego tambi\u00e9n hay prejuicios en el otro lado. Parece que est\u00e1 el cine que hace dinero, y estamos nosotros, que somos la salvaguarda de las esencias de lo que es el cine. Creo que es falso. Pedro Costa dijo una cosa que es muy divertida. Cuando una vez un periodista le pregunt\u00f3 si cre\u00eda que su cine era un cine m\u00e1s muse\u00edstico y que deb\u00eda proyectarse en museos, Costa entr\u00f3 en c\u00f3lera absoluta y le dijo que eso era un disparate, que \u00e9l quiere que proyecten <em>No quarto da Vanda <\/em>o <em>Juventude em marcha<\/em> en multicines, al lado de la \u00faltima de <em>Spiderman<\/em>. \u00c9l hace cine con gente popular, en barrios populares, y quiere que sea consumido precisamente por ese tipo de p\u00fablicos, no para las altas esferas que digan \u201coh, \u00a1c\u00f3mo viven los pobres!\u201d. Dice que ese punto de vista est\u00e1 completamente equivocado, y que \u00e9l hace cine para que sea visto por el mayor n\u00famero de gente posible. En ese sentido, no me parece que haya un prop\u00f3sito m\u00e1s digno. La clave es esa: no renunciar a la dignidad de tu trabajo por el hecho de que vayas a hacer algo relacionado al gran p\u00fablico. Eso es lo m\u00e1s importante para m\u00ed.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"656\" height=\"480\" data-id=\"5112\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Juventude-Em-Marcha-Pedro-Costa-2006.mkv_snapshot_01.56.29.497.png\" alt=\"\" class=\"wp-image-5112\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Juventude-Em-Marcha-Pedro-Costa-2006.mkv_snapshot_01.56.29.497.png 656w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Juventude-Em-Marcha-Pedro-Costa-2006.mkv_snapshot_01.56.29.497-300x220.png 300w\" sizes=\"(max-width: 656px) 100vw, 656px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"755\" data-id=\"5113\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/No-Quarto-da-Vanda-Pedro-Costa-2000.mkv_snapshot_00.11.07.449-1024x755.png\" alt=\"\" class=\"wp-image-5113\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/No-Quarto-da-Vanda-Pedro-Costa-2000.mkv_snapshot_00.11.07.449-1024x755.png 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/No-Quarto-da-Vanda-Pedro-Costa-2000.mkv_snapshot_00.11.07.449-300x221.png 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/No-Quarto-da-Vanda-Pedro-Costa-2000.mkv_snapshot_00.11.07.449-768x566.png 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/No-Quarto-da-Vanda-Pedro-Costa-2000.mkv_snapshot_00.11.07.449.png 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<figcaption class=\"blocks-gallery-caption\"><em>Junventude em marcha<\/em> (Pedro Costa, 2006) \/ <em>No quarto da Vanda <\/em>(Pedro Costa, 2000)<\/figcaption><\/figure>\n\n\n\n<div style=\"height:11px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>IB: S\u00ed, e inclusive al rev\u00e9s, porque los festivales muchas veces se cierran en s\u00ed mismos con l\u00f3gicas en favor de cierto tipo de productos, y terminan favoreciendo formas de funcionamiento y reproducci\u00f3n de lo mismo, que son muy similares a las del <em>mainstream<\/em>.<\/strong><\/p>\n\n\n\n<p>JT: Y las tem\u00e1ticas tambi\u00e9n son intercambiables, por eso precisamente hay un cine que se conoce como \u201ccine de festivales\u201d. Si bien lo tiene m\u00e1s dif\u00edcil en los circuitos comerciales, es un tipo de cine muy concreto, que, al igual que el <em>mainstream,<\/em> tiene unas reglas muy concretas. As\u00ed que al final no es algo tan libre y tan intelectual como pueda parecer; a veces hay una especie de patr\u00f3n muy bien construido, de cara a \u201cvamos a hacer una pel\u00edcula para que en Rotterdam vaya bien, para que en Locarno funcione, o para que vaya a abrir la secci\u00f3n \u2018nuevas miradas\u2019 del Festival de Venecia\u201d. Trabajo como programador de festivales, por lo que tengo que ver mucho, mucho cine, y acabo viendo patrones que se repiten una y otra vez.&nbsp;<\/p>\n\n\n\n<p>Tambi\u00e9n es verdad que el tema de las ayudas es muy importante a la hora de conseguir romper esa brecha que no cesa, pero ah\u00ed tambi\u00e9n se cuelan propuestas que se aprovechan de ese tipo de componendas; pel\u00edculas que son pl\u00fambeas, pero que tienen buena puntuaci\u00f3n, buenas subvenciones y dem\u00e1s. As\u00ed que bueno, esas son las peque\u00f1as trampas, que por otra parte creo que son inevitables.<\/p>\n\n\n\n<p><strong>IB: A partir de lo que venimos haciendo en \u201cArchivo docente\u201d, que hasta ahora han sido entrevistas a docentes de cine que trabajan en Argentina \u00bfqu\u00e9 pod\u00e9s decir con respecto a Espa\u00f1a, c\u00f3mo es la ense\u00f1anza del cine all\u00e1?<\/strong><\/p>\n\n\n\n<p>JT: Creo que la diferencia m\u00e1s grande es que la ense\u00f1anza de cine aqu\u00ed muchas veces est\u00e1 estructurada como si fuera una carrera m\u00e1s, y que el objetivo primordial es conseguir trabajo. As\u00ed que \u201cvamos a dejar un poco la teor\u00eda a un lado y vamos a ser pr\u00e1cticos, y a ver para d\u00f3nde podemos tirar para sacar adelante nuestro trabajo\u201d. Esto conlleva que las ense\u00f1anzas en Espa\u00f1a sean muy orientadas a la industria. Se deja de lado la historia del cine, se dejan de lado a los grandes te\u00f3ricos, y se va a una concepci\u00f3n muy utilitarista del cine, practicista y en b\u00fasqueda del retorno econ\u00f3mico. Eso por una parte est\u00e1 bien, ya que siempre est\u00e1 bien salir con trabajo de un sitio, si has estudiado y has invertido dinero para ello, pero por otro lado es un peligro completo para la industria, porque al final acaban saliendo clones que manejan los mismos conceptos de lo que es bueno para triunfar, de lo que es bueno para que tu pel\u00edcula tenga \u00e9xito. Al final, el empobrecimiento de la industria a nivel creativo es muy fuerte, aunque sean productos t\u00e9cnicamente estupendos. Las escuelas en Espa\u00f1a, en cuanto a lo t\u00e9cnico, son muy \u00fatiles.<\/p>\n\n\n\n<p>Yo estudi\u00e9 una rama t\u00e9cnica, la del montaje, que me vino muy bien a la hora de comprender mejor el cine. Ahora mismo acabamos de rodar una pel\u00edcula con guion m\u00edo y de dos guionistas m\u00e1s. Me ayud\u00f3 mucho ese grado de montaje a la hora de estructurar el propio guion, de pensar en im\u00e1genes, a la hora de adelantarme un poquito al trabajo que va a hacer el director en la etapa de montaje. Creo que en esas escuelas toda la parte t\u00e9cnica es impecable, y eso se nota en la factura de las pel\u00edculas que se hacen en Espa\u00f1a. Pero falla el alma. Tambi\u00e9n creo que una escuela de cine, o cualquier escuela, necesita alentar la creatividad, lo que te diferencia de los dem\u00e1s, los caminos propios que vas eligiendo en relaci\u00f3n a lo que te gusta y a lo que no. No estar todo el tiempo contestando preguntas como \u201c\u00bfesto va a funcionar? \u00bfCu\u00e1l es el <em>target<\/em>, la salida de esto? \u00bfC\u00f3mo lo vas a vender? \u00bfQu\u00e9 <em>pitch<\/em> vas a hacerle al productor con este proyecto? \u00bfQu\u00e9 retorno?\u201d. Muchas veces me parece que la mejor forma de que tu proyecto fracase es construirlo en base a un modelo ya existente. Por ejemplo, en Espa\u00f1a, al hacer comedias se copian much\u00edsimas pel\u00edculas italianas y francesas, se hacen muchas <em>remakes<\/em> y, si bien son las que llevan p\u00fablico, son pel\u00edculas de usar y tirar. Duran en tu retina y en tu pensamiento lo que tardas en salir del cine. Esto pasa tambi\u00e9n muchas veces con el cine de g\u00e9nero.<\/p>\n\n\n\n<p>Creo que, para crear pel\u00edculas que tengan algo para decir, quiz\u00e1 el camino a la hora de estudiar sea m\u00e1s tortuoso. Quiz\u00e1 es un camino mucho m\u00e1s multidisciplinar, y tienes que picotear de aqu\u00ed y de all\u00e1, y formarte por tu cuenta tambi\u00e9n en una cosa y en otra. Adem\u00e1s, aqu\u00ed hay un problema de paro bastante grande. Ahora est\u00e1 un poco mejor, pero venimos de unos a\u00f1os muy malos, intensificados por la pandemia. As\u00ed que en las universidades est\u00e1n desapareciendo todas las asignaturas que no parezca que sirvan a un fin pr\u00e1ctico, que es un trabajo. As\u00ed que las humanidades est\u00e1n cayendo en picada. Est\u00e1n desapareciendo filosof\u00eda, historia del arte y dem\u00e1s. Estamos creando una especie de generaci\u00f3n de tecn\u00f3cratas, de economistas, con n\u00fameros en la cabeza, m\u00e1s que ideas. Y es muy peligroso construir carcasas vac\u00edas que sean unas fieras a la hora del apartado t\u00e9cnico.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"432\" data-id=\"5114\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Artvazard.Pelechian.1969.We_.fitz_.avi_snapshot_12.00.714.png\" alt=\"\" class=\"wp-image-5114\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Artvazard.Pelechian.1969.We_.fitz_.avi_snapshot_12.00.714.png 576w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Artvazard.Pelechian.1969.We_.fitz_.avi_snapshot_12.00.714-300x225.png 300w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"432\" data-id=\"5116\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Artvazard.Pelechian.1969.We_.fitz_.avi_snapshot_16.19.542.png\" alt=\"\" class=\"wp-image-5116\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Artvazard.Pelechian.1969.We_.fitz_.avi_snapshot_16.19.542.png 576w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Artvazard.Pelechian.1969.We_.fitz_.avi_snapshot_16.19.542-300x225.png 300w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"432\" data-id=\"5115\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Artvazard.Pelechian.1969.We_.fitz_.avi_snapshot_22.55.987.png\" alt=\"\" class=\"wp-image-5115\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Artvazard.Pelechian.1969.We_.fitz_.avi_snapshot_22.55.987.png 576w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Artvazard.Pelechian.1969.We_.fitz_.avi_snapshot_22.55.987-300x225.png 300w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure>\n<figcaption class=\"blocks-gallery-caption\"><em>Menq <\/em>(Artavazd Pelechian, 1969)<\/figcaption><\/figure>\n\n\n\n<div style=\"height:11px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>IB: La <em>linkedizaci\u00f3n <\/em>de la educaci\u00f3n.<\/strong><\/p>\n\n\n\n<p>JT: Eso es. En Argentina, seg\u00fan lo que he le\u00eddo en algunas entrevistas de <em>Taipei<\/em>, la parte te\u00f3rica se trabaja m\u00e1s. Creo que ten\u00e9is una tradici\u00f3n te\u00f3rica muy fuerte, muy interesante; que no descart\u00e1is esa pata como algo in\u00fatil a la hora de llevar a cabo la educaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p><strong>IB: Hasta, quiz\u00e1, por momentos demasiado te\u00f3rica.<\/strong><\/p>\n\n\n\n<p>JT: Los extremos\u2026. ya sabes. Puedes crear una especie de solipsismo con tanta teor\u00eda, y al final no llegar a ning\u00fan lado. Es como pasa en la pol\u00edtica. Aqu\u00ed tenemos un partido de izquierdas que tiene unas teor\u00edas fant\u00e1sticas, pero que cuesta un mundo llevarlas a cabo, porque son teor\u00edas que deber\u00edan arraigarse en el mundo real. Creo que hay que tener conciencia de lo que es la industria, de los p\u00fablicos y de las productoras que est\u00e1n trabajando en el pa\u00eds. Pero tienes que meter el factor diferencial que es cada uno. Me parece m\u00e1s inteligente partir de lo m\u00ednimo para llegar a lo universal: contar tu historia de la mejor forma posible es la mejor forma de llegar a todo tipo de p\u00fablicos. Dec\u00eda Larry Clark, el fot\u00f3grafo, que hay una historia que nunca se ha contado, que es la de uno mismo. Siempre va a ser diferente. Es verdad que las tem\u00e1ticas se repiten, y al final tenemos dos o tres argumentos en la historia de la humanidad desde Homero, pero lo que convierte a cada pel\u00edcula, a cada libro, a cada canci\u00f3n en algo completamente distinto es tu visi\u00f3n personal. Y eso solo lo vas a poder hacer t\u00fa. As\u00ed que creo que eso siempre se tiene que potenciar, y nunca se tiene que dejar de lado. No puedes decir \u201ca ver si eres el pr\u00f3ximo [Steven] Spielberg\u201d, tienes que ser el pr\u00f3ximo t\u00fa.<\/p>\n\n\n\n<p><strong>IB: \u00bfC\u00f3mo es el panorama de formaciones de cine que hay en Espa\u00f1a?<\/strong><\/p>\n\n\n\n<p>JT: Hay dos grandes escuelas, que est\u00e1n implantadas en las dos grandes ciudades de Espa\u00f1a: Madrid y Barcelona. En Barcelona est\u00e1 la ESCAC, la Escuela de Cine de Catalu\u00f1a, una escuela de la que salen much\u00edsimos t\u00e9cnicos como operadores de c\u00e1mara, m\u00fasicos\u2026 Es una escuela que tiene un profesorado estupendo y el clima es fant\u00e1stico. Te hablaba antes del practicismo y dem\u00e1s, pero en este caso la escuela se ha escorado desde hace mucho tiempo hacia determinado tipo de cine que, en este caso, es el cine de autor. Un cine intimista, con presupuesto medio; un tipo de cine con una l\u00ednea muy clara. Cuando hablamos, por ejemplo, de las pel\u00edculas Netflix, todos sabemos a lo que nos referimos. Aqu\u00ed, en Espa\u00f1a, las pel\u00edculas que salen de la ESCAC tambi\u00e9n tienen una p\u00e1tina muy clarificadora. En este caso, no es tan negativa como si se tratara de un cine mucho m\u00e1s industrial, de mucho m\u00e1s usar y tirar; son pel\u00edculas que tienen un poquito m\u00e1s de alma. Pero ese alma poco a poco se acaba desdibujando cuando te das cuenta de que todas tienen los mismos componentes melanc\u00f3licos, de j\u00f3venes perdidos y sin futuro, con relaciones a dos y a tres bandas, todo contado de una manera suave, sin levantar la voz; una narrativa con un lenguaje audiovisual cl\u00e1sico, que parece que est\u00e1 muy influenciado por \u00c9ric Rohmer y gente as\u00ed. Bendita influencia. Hay influencias much\u00edsimo peores, est\u00e1 claro, pero igual acaba convirti\u00e9ndose en un producto. Al final, el producto ESCAC est\u00e1 clar\u00edsimo en el panorama audiovisual espa\u00f1ol.<\/p>\n\n\n\n<p>Por otro lado, est\u00e1 la ECAM, que es la Escuela de Cine de Madrid, y es una escuela pr\u00e1ctica: la gente sale de ah\u00ed con trabajo. Es un decir, porque tampoco puedes pretender hacer un m\u00f3dulo de direcci\u00f3n de cine y salir virgen a hacer una pel\u00edcula; no creo que nadie lo piense. Adem\u00e1s, en el fondo es la suma de todo el resto de ramas, ya que un director de cine tiene que saber absolutamente de todo.&nbsp;<\/p>\n\n\n\n<p>Aparte de eso, hay un mont\u00f3n de escuelas de comunicaci\u00f3n audiovisual y de formaci\u00f3n profesional \u2014que no son grados universitarios pero son escuelas superiores. Ah\u00ed hay de todo: escuelas ultra t\u00e9cnicas, para salir de ah\u00ed siendo un fant\u00e1stico operador de c\u00e1mara, y luego hay otras escuelas m\u00e1s te\u00f3ricas. El tipo de clase que yo doy es sobre todo para gente que tenga inter\u00e9s en el cine, no tanto a nivel profesional, para labrarse un futuro nuevo, sino como curiosidad, por el hecho del hacer cinematogr\u00e1fico \u2014no solo del arte cinematogr\u00e1fico, sino tambi\u00e9n la fotograf\u00eda, la literatura y otras artes. De hecho, yo he tendido cada vez m\u00e1s en mis cursos, talleres y seminarios a mezclarlo absolutamente todo, y he acabado hablando de poes\u00eda, de fotograf\u00eda, de m\u00fasica y de cine casi de casualidad. Pero, para m\u00ed, todo es cine. En mi d\u00eda a d\u00eda me alimento much\u00edsimo de libros, de videoarte, de m\u00fasica, y todo al final acaba teniendo alg\u00fan tipo de resonancia en mi trabajo de guionista, en mi trabajo de gesti\u00f3n cultural y en mi trabajo de programaci\u00f3n. Creo que lo bonito del cine es precisamente eso, que es un arte que se nutre de la vida. As\u00ed que cuando a veces la gente me pregunta \u201cqu\u00e9 tengo que hacer para\u2026\u201d, yo les digo que tengan sobre todo curiosidad. Curiosidad por lo que te rodea, ver todas las pel\u00edculas que puedas, leer todos los libros que puedas, tener todas las experiencias que puedas, estar todo el tiempo atento a lo que pasa a tu alrededor.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Spider-Man.No_.Way_.Home_.2021.1080p.BluRay.x265-RARBG.mp4_snapshot_02.00.51.789-1024x429.png\" alt=\"\" class=\"wp-image-5122\" width=\"614\" height=\"257\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Spider-Man.No_.Way_.Home_.2021.1080p.BluRay.x265-RARBG.mp4_snapshot_02.00.51.789-1024x429.png 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Spider-Man.No_.Way_.Home_.2021.1080p.BluRay.x265-RARBG.mp4_snapshot_02.00.51.789-300x126.png 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Spider-Man.No_.Way_.Home_.2021.1080p.BluRay.x265-RARBG.mp4_snapshot_02.00.51.789-768x322.png 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Spider-Man.No_.Way_.Home_.2021.1080p.BluRay.x265-RARBG.mp4_snapshot_02.00.51.789-1536x643.png 1536w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Spider-Man.No_.Way_.Home_.2021.1080p.BluRay.x265-RARBG.mp4_snapshot_02.00.51.789.png 1920w\" sizes=\"(max-width: 614px) 100vw, 614px\" \/><figcaption><em>Spider-Man: No Way Home <\/em>(Jon Watts, 2021)<\/figcaption><\/figure>\n<\/div>\n\n\n<p><strong>IB: Escuch\u00e1ndote, me da la sensaci\u00f3n de que todos los estudiantes salen haciendo el mismo tipo de cine, y eso es un delito pedag\u00f3gico.<\/strong><\/p>\n\n\n\n<p>JT: Yo lo tengo claro, y mira que las referencias son estupendas: [\u00c9ric] Rohmer, Agn\u00e8s Varda\u2026 Pero no puede ser que hagas una especie de <em>nouvelle vague<\/em> en Catalu\u00f1a en 2022. \u00bfPor qu\u00e9, para qu\u00e9? Haz cine catal\u00e1n de 2022. No hagas cine remedando lo que ya se hizo, es un disparate. Que lo hagan los ni\u00f1os estos de Bergala, de 8 y 9 a\u00f1os, es maravilloso, y eso s\u00ed que me parece un aprendizaje fant\u00e1stico. Pero cuando ya tienes una edad y quieres hacer tus cosas, pues no s\u00e9, haz las tuyas.<\/p>\n\n\n\n<p><strong>IB: S\u00ed, y m\u00e1s que nada en un circuito \u2014que es un mercado\u2014 que pone en primer plano la idea del autor. Entonces hay un problema ah\u00ed, de formar autores con m\u00e9todos y resultados en los que, si empez\u00e1s a leer entre l\u00edneas, mucha autor\u00eda no hay.&nbsp;Quer\u00eda preguntarte, en relaci\u00f3n a esto y m\u00e1s all\u00e1 de tu trabajo concreto en CESUGA, \u00bfqu\u00e9 pens\u00e1s que habr\u00eda que haber en una clase de guion para que pueda surgir diversidad cinematogr\u00e1fica?<\/strong><\/p>\n\n\n\n<p>JT: Cuando empec\u00e9 a escribir guiones de cine, hice lo que supongo que hace todo el mundo, que es leer todos estos manuales de Robert McKee, de Syd Field, de Linda Seger, todos los cl\u00e1sicos b\u00e1sicos; <em>\u00a1Salva al gato!<\/em>, ese tipo de cosas. Me los le\u00ed todos, y me parecieron un disparate. Porque te dicen cosas como \u201cen la p\u00e1gina 67 tienes que tener un punto de giro, y en la 72 el h\u00e9roe tiene que tener determinada cosa\u201d. Una especie de estructura matem\u00e1tica que, volvemos a lo mismo, usa modelos de pel\u00edculas comerciales como <em>Regreso al futuro<\/em> o<em> Tras el coraz\u00f3n verde<\/em><sup><a href=\"#nota1\">(1)<\/a><\/sup>. No tengo nada contra ellas, pero no entiendo por qu\u00e9 tenemos que volver a hacer esas pel\u00edculas. Despu\u00e9s de leer toda esa literatura de manuales de guion me qued\u00e9 con unos libros m\u00e1s peque\u00f1os: uno de Michel Chion, que es un fant\u00e1stico te\u00f3rico tambi\u00e9n, y otro de Jean-Claude Carri\u00e8re, que ha sido guionista de Luis Bu\u00f1uel y dem\u00e1s. Sobre todo con el de Carri\u00e8re, que debe tener como mucho cien p\u00e1ginas: <em>The End: Pr\u00e1ctica del guion cinematogr\u00e1fico<\/em>. Lo que me gusta del libro es que es un libro pr\u00e1ctico, que es un t\u00edo hablando de su trabajo como guionista, de su trabajo real, sin pajas mentales, sin ponerse a hablar de lo divino y de lo humano, y hacer f\u00f3rmulas matem\u00e1ticas. Lo que te cuenta son los problemas a los que se enfrent\u00f3 como guionista, trabajando para el cine, y ya est\u00e1.&nbsp;<\/p>\n\n\n\n<p>Luego te das cuenta que a todos estos, Robert McKee y dem\u00e1s, los buscas en IMDb y la filmograf\u00eda es un desastre absoluto. Ah\u00ed hay algo que no funciona: \u00bfme va a ense\u00f1ar \u00e9ste, que es el mejor profesor de guion del mundo y nunca ha escrito nada m\u00ednimamente decente? Ah\u00ed hay algo que realmente no funciona. Yo quiero saber las cosas que pasan realmente cuando se escribe un guion, los desaf\u00edos que se te presentan, los problemas que pueden tener, c\u00f3mo tienes que hacer el trabajo en conjunto con el director, con otro guionista, c\u00f3mo trabajas en la televisi\u00f3n con quince guionistas m\u00e1s, c\u00f3mo coordinas una secci\u00f3n, c\u00f3mo haces un guion en directo, cu\u00e1les son los trucos para sacar un programa diario. En cuanto al cine, c\u00f3mo puedes utilizar lo que has visto, pero no a modo de homenaje, que es una cosa que me horroriza, de hacer homenajes y gui\u00f1os, y poner un p\u00f3ster aqu\u00ed de [John] Carpenter para que la gente vea que te gusta mucho el cine de serie B y esas tonter\u00edas. Yo creo que, en ese sentido, las clases tienen que ser pr\u00e1cticas y lo que tienes que contar es tu experiencia. Hablar a los alumnos desde lo que has hecho t\u00fa, de cosas reales y tangibles, no desde teor\u00edas rocambolescas que se te puedan ocurrir, ni desde f\u00f3rmulas.<\/p>\n\n\n\n<p>Yo hago muchas cosas, y creo que todas las hago medio regular. Pero lo que mejor hago es ser espectador. Eso para m\u00ed es muy importante: entender lo que te est\u00e1n planteando al otro lado de la pantalla, porque ah\u00ed es cuando t\u00fa vas a entender un poco c\u00f3mo realizar tu trabajo. Y no va a ser copiar, sino que va a ser entender c\u00f3mo funcionan las pel\u00edculas, entender c\u00f3mo funciona el lenguaje cinematogr\u00e1fico, y eso es en lo que te tienes que fijar. Hacer un an\u00e1lisis real. Cuando una pel\u00edcula te gusta, tienes que pararte e intentar entender por qu\u00e9 te gusta. Si un guion te gusta, tienes que volver a leer ese guion en papel, y ver si en papel tambi\u00e9n funciona, o ver si de repente ha habido un cambio brutal del papel a la pantalla. Esas son las cosas que tienes que entender. Cuando entiendas por qu\u00e9 funciona equis guion, ah\u00ed es cuando vas a empezar a aprender, y no porque alguien te diga que en la p\u00e1gina 20 hay que meter un punto de giro.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"555\" data-id=\"5119\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Back.to_.the_.Future.1985.1080p.BluRay.H264.AAC-RARBG.mp4_snapshot_00.23.46.907-1024x555.png\" alt=\"\" class=\"wp-image-5119\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Back.to_.the_.Future.1985.1080p.BluRay.H264.AAC-RARBG.mp4_snapshot_00.23.46.907-1024x555.png 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Back.to_.the_.Future.1985.1080p.BluRay.H264.AAC-RARBG.mp4_snapshot_00.23.46.907-300x163.png 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Back.to_.the_.Future.1985.1080p.BluRay.H264.AAC-RARBG.mp4_snapshot_00.23.46.907-768x416.png 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Back.to_.the_.Future.1985.1080p.BluRay.H264.AAC-RARBG.mp4_snapshot_00.23.46.907-1536x832.png 1536w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Back.to_.the_.Future.1985.1080p.BluRay.H264.AAC-RARBG.mp4_snapshot_00.23.46.907.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"555\" data-id=\"5120\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Back.to_.the_.Future.1985.1080p.BluRay.H264.AAC-RARBG.mp4_snapshot_01.38.14.444-1024x555.png\" alt=\"\" class=\"wp-image-5120\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Back.to_.the_.Future.1985.1080p.BluRay.H264.AAC-RARBG.mp4_snapshot_01.38.14.444-1024x555.png 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Back.to_.the_.Future.1985.1080p.BluRay.H264.AAC-RARBG.mp4_snapshot_01.38.14.444-300x163.png 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Back.to_.the_.Future.1985.1080p.BluRay.H264.AAC-RARBG.mp4_snapshot_01.38.14.444-768x416.png 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Back.to_.the_.Future.1985.1080p.BluRay.H264.AAC-RARBG.mp4_snapshot_01.38.14.444-1536x832.png 1536w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/Back.to_.the_.Future.1985.1080p.BluRay.H264.AAC-RARBG.mp4_snapshot_01.38.14.444.png 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<figcaption class=\"blocks-gallery-caption\"><em>Back to the Future<\/em> (Robert Zemeckis, 1985)<\/figcaption><\/figure>\n\n\n\n<div style=\"height:11px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>IB: Claro, porque la idea misma de reglas matem\u00e1ticas para diagramar narrativas no solo no dialoga con la po\u00e9tica particular de la pel\u00edcula \u2014que ya de antemano, al aceptar estas teor\u00edas, no existe\u2014 sino que tampoco tiene v\u00ednculo con lo que efectivamente sucede en la pel\u00edcula. Es directamente antidram\u00e1tico. La aplicaci\u00f3n de esta teor\u00eda a pie juntillas no mide el impacto emocional que genera lo que efectivamente ocurre en cada pel\u00edcula, como algo singular y con efectos espec\u00edficos.<\/strong><\/p>\n\n\n\n<p>JT: Cada pel\u00edcula es un mundo, y el que diga lo contrario miente completamente. A m\u00ed me gusta much\u00edsimo el cine de g\u00e9nero \u2014de hecho, todo lo que escribo es de g\u00e9nero\u2014, y dentro del g\u00e9nero las posibilidades son infinitas. El cine de terror es una especie de gueto muy acotado, con reglas muy espec\u00edficas y dem\u00e1s. Precisamente me gusta por eso, porque parece que hay un corset del que no puedes salir, pero en cambio las variaciones son infinitas. Recuerdo que en unas clases de guion que hice con un guionista que hab\u00eda trabajado con Bu\u00f1uel, hab\u00eda dos ejercicios. Uno era una p\u00e1gina en blanco, en el cual pod\u00edamos hacer el guion que se nos diera la gana, y para el otro nos daba un guion pr\u00e1cticamente cerrado, con muy poco margen de maniobra. El resultado era que los guiones que sal\u00edan de ese segundo trabajo eran mil veces m\u00e1s brillantes, creativos, imaginativos y libres que el de la p\u00e1gina en blanco, que eran unos relatos amorfos en los que, por miedo, se hac\u00edan cosas de lo m\u00e1s convencionales. En cambio, cuando te cierran mucho, necesitas liberarte de alguna manera, y ah\u00ed la creatividad crece, que es lo que pasa con el g\u00e9nero de terror. O por lo menos a m\u00ed me pasa. En ese sentido, cuando escrib\u00ed el guion de la \u00faltima pel\u00edcula en la que trabaj\u00e9, en ning\u00fan momento me plante\u00e9 si estaba cumpliendo m\u00e1s o menos la estructura convencional o no. Fue a posteriori que le echamos un ojo y vimos que m\u00e1s o menos iba niquelada. Pero eso tiene que salir porque s\u00ed. Y si no hubiera salido niquelada es porque la pel\u00edcula no hubiera necesitado eso, necesitar\u00eda otra cosa. As\u00ed que, nada: McKee, mu\u00e9rete.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-small-font-size\"><strong>Nota:<\/strong><\/p>\n\n\n\n<p class=\"has-small-font-size\" id=\"nota1\"><strong>1<\/strong> El entrevistado hace referencia a dos films de Robert Zemeckis estrenados con t\u00edtulos diferentes en Latinoam\u00e9rica: <em>Volver al futuro<\/em> (<em>Back to the Future<\/em>, 1985) y <em>Tras la esmeralda perdida<\/em> (<em>Romancing the Stone<\/em>, 1984). [N. del E.]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ense\u00f1anza de cine en Espa\u00f1a est\u00e1 muy orientada a la industria. Se deja de lado la historia del cine, se dejan de lado a los grandes te\u00f3ricos, y se va a una concepci\u00f3n muy utilitarista del cine, practicista y en b\u00fasqueda del retorno econ\u00f3mico. Eso por una parte est\u00e1 bien, ya que siempre est\u00e1 bien salir con trabajo de un sitio, pero por otro lado es un peligro completo para la industria, porque acaban saliendo clones que manejan los mismos conceptos de lo que es bueno para que tu pel\u00edcula tenga \u00e9xito. Al final, el empobrecimiento de la industria a nivel creativo es muy fuerte, aunque sean productos t\u00e9cnicamente estupendos(&#8230;)<\/p>\n","protected":false},"author":2,"featured_media":5110,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[56],"tags":[777,417,501,619,780,82,779,775,778,776],"class_list":{"0":"post-5109","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-educacion","8":"tag-alain-bergala","9":"tag-archivo-docente","10":"tag-cine-espanol","11":"tag-cine-y-educacion","12":"tag-ecam","13":"tag-educacion","14":"tag-escac","15":"tag-javier-trigales","16":"tag-pedro-costa","17":"tag-robert-mckee"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La muerte de Robert McKee | Javier Trigales, docente de guion<\/title>\n<meta name=\"description\" content=\"La ense\u00f1anza de cine en Espa\u00f1a est\u00e1 muy orientada a la industria. Una concepci\u00f3n utilitarista del cine, en busca del retorno econ\u00f3mico (...)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/taipeirevista.com\/index.php\/2022\/04\/08\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La muerte de Robert McKee | Javier Trigales, docente de guion\" \/>\n<meta property=\"og:description\" content=\"La ense\u00f1anza de cine en Espa\u00f1a est\u00e1 muy orientada a la industria. Una concepci\u00f3n utilitarista del cine, en busca del retorno econ\u00f3mico (...)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/taipeirevista.com\/index.php\/2022\/04\/08\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\/\" \/>\n<meta property=\"og:site_name\" content=\"TAIPEI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revistataipei\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-08T12:00:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-09T08:26:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/javier-trigales-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1439\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Iv\u00e1n Bustinduy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@taipeicritica\" \/>\n<meta name=\"twitter:site\" content=\"@taipeicritica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Iv\u00e1n Bustinduy\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"25 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2022\\\/04\\\/08\\\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2022\\\/04\\\/08\\\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\\\/\"},\"author\":{\"name\":\"Iv\u00e1n Bustinduy\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#\\\/schema\\\/person\\\/8f7642517bfc0525cd7deb8a46551158\"},\"headline\":\"La muerte de Robert McKee. Entrevista a Javier Trigales, docente de guion\",\"datePublished\":\"2022-04-08T12:00:16+00:00\",\"dateModified\":\"2022-08-09T08:26:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2022\\\/04\\\/08\\\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\\\/\"},\"wordCount\":5263,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2022\\\/04\\\/08\\\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/taipeirevista.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/javier-trigales-scaled.jpg\",\"keywords\":[\"Alain Bergala\",\"Archivo docente\",\"Cine espa\u00f1ol\",\"Cine y educaci\u00f3n\",\"ECAM\",\"Educaci\u00f3n\",\"ESCAC\",\"Javier Trigales\",\"Pedro Costa\",\"Robert McKee\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2022\\\/04\\\/08\\\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2022\\\/04\\\/08\\\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\\\/\",\"url\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2022\\\/04\\\/08\\\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\\\/\",\"name\":\"La muerte de Robert McKee | Javier Trigales, docente de guion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2022\\\/04\\\/08\\\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2022\\\/04\\\/08\\\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/taipeirevista.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/javier-trigales-scaled.jpg\",\"datePublished\":\"2022-04-08T12:00:16+00:00\",\"dateModified\":\"2022-08-09T08:26:38+00:00\",\"description\":\"La ense\u00f1anza de cine en Espa\u00f1a est\u00e1 muy orientada a la industria. Una concepci\u00f3n utilitarista del cine, en busca del retorno econ\u00f3mico (...)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2022\\\/04\\\/08\\\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2022\\\/04\\\/08\\\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2022\\\/04\\\/08\\\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/taipeirevista.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/javier-trigales-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/taipeirevista.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/javier-trigales-scaled.jpg\",\"width\":2560,\"height\":1439},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2022\\\/04\\\/08\\\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/taipeirevista.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La muerte de Robert McKee. Entrevista a Javier Trigales, docente de guion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#website\",\"url\":\"https:\\\/\\\/taipeirevista.com\\\/\",\"name\":\"TAIPEI\",\"description\":\"Cr\u00edtica de cine\",\"publisher\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/taipeirevista.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#organization\",\"name\":\"Taipei \\\/ Cr\u00edtica de cine\",\"url\":\"https:\\\/\\\/taipeirevista.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/taipeirevista.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/TAIPEI-LOGO-1.1-SIN-GRIS.png\",\"contentUrl\":\"https:\\\/\\\/taipeirevista.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/TAIPEI-LOGO-1.1-SIN-GRIS.png\",\"width\":599,\"height\":599,\"caption\":\"Taipei \\\/ Cr\u00edtica de cine\"},\"image\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/revistataipei\",\"https:\\\/\\\/x.com\\\/taipeicritica\",\"https:\\\/\\\/www.instagram.com\\\/taipeicritica\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#\\\/schema\\\/person\\\/8f7642517bfc0525cd7deb8a46551158\",\"name\":\"Iv\u00e1n Bustinduy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33a83bcd8813d5df410ca38aad13b35c97807dbcd765337fc381f40b743c1a75?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33a83bcd8813d5df410ca38aad13b35c97807dbcd765337fc381f40b743c1a75?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33a83bcd8813d5df410ca38aad13b35c97807dbcd765337fc381f40b743c1a75?s=96&d=mm&r=g\",\"caption\":\"Iv\u00e1n Bustinduy\"},\"description\":\"Naci\u00f3 en Buenos Aires en 1997. Se form\u00f3 como realizador cinematogr\u00e1fico y profesor en la Universidad del Cine (FUC), donde trabaja como docente. Dirigi\u00f3 los cortometrajes El segundo hombre (2021), ganador del Premio M\u00e9li\u00e8s en el Festival de Cine de Mar del Plata, y Carga animal (2022), con estreno en BAFICI, P\u00d6FF Shorts y Palm Springs. Es coordinador del Colectivo Rutemberg, productora con base en Buenos Aires, y de TAIPEI \\\/ Cr\u00edtica de cine, donde escribe sobre cine y educaci\u00f3n. Trabaja como director de programaci\u00f3n en Guayaba, una plataforma de cine latinoamericano. Actualmente cursa el M\u00e1ster de Comisariado en El\u00edas Querejeta Zine Eskola (EQZE) mientras desarrolla Tiempo fuera, su \u00f3pera prima. Contacto: bustinduyivan@gmail.com.\",\"sameAs\":[\"http:\\\/\\\/taipeirevista.com\"],\"url\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/author\\\/ivanb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La muerte de Robert McKee | Javier Trigales, docente de guion","description":"La ense\u00f1anza de cine en Espa\u00f1a est\u00e1 muy orientada a la industria. Una concepci\u00f3n utilitarista del cine, en busca del retorno econ\u00f3mico (...)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/taipeirevista.com\/index.php\/2022\/04\/08\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\/","og_locale":"es_ES","og_type":"article","og_title":"La muerte de Robert McKee | Javier Trigales, docente de guion","og_description":"La ense\u00f1anza de cine en Espa\u00f1a est\u00e1 muy orientada a la industria. Una concepci\u00f3n utilitarista del cine, en busca del retorno econ\u00f3mico (...)","og_url":"https:\/\/taipeirevista.com\/index.php\/2022\/04\/08\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\/","og_site_name":"TAIPEI","article_publisher":"https:\/\/www.facebook.com\/revistataipei","article_published_time":"2022-04-08T12:00:16+00:00","article_modified_time":"2022-08-09T08:26:38+00:00","og_image":[{"width":2560,"height":1439,"url":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/javier-trigales-scaled.jpg","type":"image\/jpeg"}],"author":"Iv\u00e1n Bustinduy","twitter_card":"summary_large_image","twitter_creator":"@taipeicritica","twitter_site":"@taipeicritica","twitter_misc":{"Escrito por":"Iv\u00e1n Bustinduy","Tiempo de lectura":"25 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/taipeirevista.com\/index.php\/2022\/04\/08\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\/#article","isPartOf":{"@id":"https:\/\/taipeirevista.com\/index.php\/2022\/04\/08\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\/"},"author":{"name":"Iv\u00e1n Bustinduy","@id":"https:\/\/taipeirevista.com\/#\/schema\/person\/8f7642517bfc0525cd7deb8a46551158"},"headline":"La muerte de Robert McKee. Entrevista a Javier Trigales, docente de guion","datePublished":"2022-04-08T12:00:16+00:00","dateModified":"2022-08-09T08:26:38+00:00","mainEntityOfPage":{"@id":"https:\/\/taipeirevista.com\/index.php\/2022\/04\/08\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\/"},"wordCount":5263,"commentCount":0,"publisher":{"@id":"https:\/\/taipeirevista.com\/#organization"},"image":{"@id":"https:\/\/taipeirevista.com\/index.php\/2022\/04\/08\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\/#primaryimage"},"thumbnailUrl":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/javier-trigales-scaled.jpg","keywords":["Alain Bergala","Archivo docente","Cine espa\u00f1ol","Cine y educaci\u00f3n","ECAM","Educaci\u00f3n","ESCAC","Javier Trigales","Pedro Costa","Robert McKee"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/taipeirevista.com\/index.php\/2022\/04\/08\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/taipeirevista.com\/index.php\/2022\/04\/08\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\/","url":"https:\/\/taipeirevista.com\/index.php\/2022\/04\/08\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\/","name":"La muerte de Robert McKee | Javier Trigales, docente de guion","isPartOf":{"@id":"https:\/\/taipeirevista.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/taipeirevista.com\/index.php\/2022\/04\/08\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\/#primaryimage"},"image":{"@id":"https:\/\/taipeirevista.com\/index.php\/2022\/04\/08\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\/#primaryimage"},"thumbnailUrl":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/javier-trigales-scaled.jpg","datePublished":"2022-04-08T12:00:16+00:00","dateModified":"2022-08-09T08:26:38+00:00","description":"La ense\u00f1anza de cine en Espa\u00f1a est\u00e1 muy orientada a la industria. Una concepci\u00f3n utilitarista del cine, en busca del retorno econ\u00f3mico (...)","breadcrumb":{"@id":"https:\/\/taipeirevista.com\/index.php\/2022\/04\/08\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/taipeirevista.com\/index.php\/2022\/04\/08\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/taipeirevista.com\/index.php\/2022\/04\/08\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\/#primaryimage","url":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/javier-trigales-scaled.jpg","contentUrl":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/javier-trigales-scaled.jpg","width":2560,"height":1439},{"@type":"BreadcrumbList","@id":"https:\/\/taipeirevista.com\/index.php\/2022\/04\/08\/la-muerte-de-robert-mckee-entrevista-a-javier-trigales-docente-de-guion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/taipeirevista.com\/"},{"@type":"ListItem","position":2,"name":"La muerte de Robert McKee. Entrevista a Javier Trigales, docente de guion"}]},{"@type":"WebSite","@id":"https:\/\/taipeirevista.com\/#website","url":"https:\/\/taipeirevista.com\/","name":"TAIPEI","description":"Cr\u00edtica de cine","publisher":{"@id":"https:\/\/taipeirevista.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/taipeirevista.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/taipeirevista.com\/#organization","name":"Taipei \/ Cr\u00edtica de cine","url":"https:\/\/taipeirevista.com\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/taipeirevista.com\/#\/schema\/logo\/image\/","url":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/08\/TAIPEI-LOGO-1.1-SIN-GRIS.png","contentUrl":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/08\/TAIPEI-LOGO-1.1-SIN-GRIS.png","width":599,"height":599,"caption":"Taipei \/ Cr\u00edtica de cine"},"image":{"@id":"https:\/\/taipeirevista.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/revistataipei","https:\/\/x.com\/taipeicritica","https:\/\/www.instagram.com\/taipeicritica\/"]},{"@type":"Person","@id":"https:\/\/taipeirevista.com\/#\/schema\/person\/8f7642517bfc0525cd7deb8a46551158","name":"Iv\u00e1n Bustinduy","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/33a83bcd8813d5df410ca38aad13b35c97807dbcd765337fc381f40b743c1a75?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/33a83bcd8813d5df410ca38aad13b35c97807dbcd765337fc381f40b743c1a75?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/33a83bcd8813d5df410ca38aad13b35c97807dbcd765337fc381f40b743c1a75?s=96&d=mm&r=g","caption":"Iv\u00e1n Bustinduy"},"description":"Naci\u00f3 en Buenos Aires en 1997. Se form\u00f3 como realizador cinematogr\u00e1fico y profesor en la Universidad del Cine (FUC), donde trabaja como docente. Dirigi\u00f3 los cortometrajes El segundo hombre (2021), ganador del Premio M\u00e9li\u00e8s en el Festival de Cine de Mar del Plata, y Carga animal (2022), con estreno en BAFICI, P\u00d6FF Shorts y Palm Springs. Es coordinador del Colectivo Rutemberg, productora con base en Buenos Aires, y de TAIPEI \/ Cr\u00edtica de cine, donde escribe sobre cine y educaci\u00f3n. Trabaja como director de programaci\u00f3n en Guayaba, una plataforma de cine latinoamericano. Actualmente cursa el M\u00e1ster de Comisariado en El\u00edas Querejeta Zine Eskola (EQZE) mientras desarrolla Tiempo fuera, su \u00f3pera prima. Contacto: bustinduyivan@gmail.com.","sameAs":["http:\/\/taipeirevista.com"],"url":"https:\/\/taipeirevista.com\/index.php\/author\/ivanb\/"}]}},"jetpack_featured_media_url":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/04\/javier-trigales-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/posts\/5109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/comments?post=5109"}],"version-history":[{"count":13,"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/posts\/5109\/revisions"}],"predecessor-version":[{"id":6009,"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/posts\/5109\/revisions\/6009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/media\/5110"}],"wp:attachment":[{"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/media?parent=5109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/categories?post=5109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/tags?post=5109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}