{"id":7047,"date":"2023-02-10T15:56:42","date_gmt":"2023-02-10T15:56:42","guid":{"rendered":"https:\/\/taipeirevista.com\/?p=7047"},"modified":"2023-02-11T00:54:34","modified_gmt":"2023-02-11T00:54:34","slug":"una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca","status":"publish","type":"post","link":"https:\/\/taipeirevista.com\/index.php\/2023\/02\/10\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\/","title":{"rendered":"\u201cUna programaci\u00f3n que mire m\u00e1s hacia afuera\u201d. Beatriz Bartolom\u00e9 Herrera, coordinadora en Cineteca"},"content":{"rendered":"\n<p><em>Beatriz Bartolom\u00e9 Herrera es gestora cultural, docente e investigadora. Conversamos con ella para conocer los dos programas de formaci\u00f3n cinematogr\u00e1fica que gestiona en Cineteca<\/em><sup><a href=\"#nota1\">(1)<\/a><\/sup><em>: <\/em><a href=\"https:\/\/www.cinetecamadrid.com\/ciclo\/escuela-dentro-cine\">Dentro Cine<\/a><em>, un proyecto experimental de educaci\u00f3n art\u00edstica para j\u00f3venes en situaci\u00f3n de vulnerabilidad, y <\/em><a href=\"https:\/\/www.cinetecamadrid.com\/secciones\/cinezeta-jovenes-programando\">CineZeta<\/a><em>, uno de los pocos proyectos de formaci\u00f3n en programaci\u00f3n de cine de Iberoam\u00e9rica.<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-right has-text-color has-small-font-size\" style=\"color:#526368\"><strong>CINE EN LAS AULAS, AULAS EN EL CINE #2<\/strong><\/p>\n\n\n\n<div style=\"height:13px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>\u00bfEn qu\u00e9 consiste <\/strong><strong><em>Aula sin fin <\/em><\/strong><strong>y qu\u00e9 proyectos engloba?<\/strong><\/p>\n\n\n\n<p><em>Aula sin fin <\/em>nace en 2018. Es un homenaje a Jos\u00e9 Val del Omar, ya que retoma la idea de \u201csin fin\u201d que aparec\u00eda al final de su \u201cTr\u00edptico elemental de Espa\u00f1a\u201d, pensando la programaci\u00f3n como un espacio abierto. Es decir, no hacer propuestas cerradas, con un principio y un final, o demasiado desarrolladas, sino propuestas que est\u00e9n m\u00e1s bien vivas, donde tanto el equipo de programaci\u00f3n como el propio p\u00fablico participen d\u00e1ndole vida y forma a partir del di\u00e1logo. Un poco la idea de \u201csin fin\u201d viene de ah\u00ed, de pensar una Cineteca abierta y viva.&nbsp;<\/p>\n\n\n\n<p>Si bien estamos repensando algunas de las actividades y proyecciones, actualmente llevamos adelante el proyecto <em>Escuela Dentro Cine<\/em>, que hacemos junto a la Direcci\u00f3n General de Familias e Infancia del Ayuntamiento de Madrid \u2014dentro del programa ASPA\u2014 y la Fundaci\u00f3n Balia. Las dos tienen programas dedicados a ofrecer apoyo a j\u00f3venes en situaci\u00f3n de vulnerabilidad, y este proyecto que nos re\u00fane surge al encontrarnos con el trabajo del cineasta Pedro Sara y la psicoterapeuta y tambi\u00e9n cineasta Violeta Pag\u00e1n. Ellos llevaban a cabo un proyecto de trabajo con j\u00f3venes en centros de menores, con los que desarrollaban proyectos cinematogr\u00e1ficos. Lo que pasa es que muchas veces estos proyectos de car\u00e1cter social son muy cortos, muy puntuales en su desarrollo, o presentan a lo mejor un perfil un poco paternalista. Creo que lo m\u00e1s interesante de <em>Escuela Dentro Cine<\/em> es que a lo largo de las distintas ediciones se ha ido trabajando para que quienes forman parte del equipo no sean solo part\u00edcipes del proyecto, sino que tambi\u00e9n lleven adelante los proyectos cinematogr\u00e1ficos que se desarrollan dentro de la Escuela: los lideren, los hagan suyos. Tambi\u00e9n, a ellos mismos, esto los legitima como artistas y como creadores, m\u00e1s all\u00e1 de ser solamente sujetos de un proyecto.&nbsp;<\/p>\n\n\n\n<p>El proyecto empez\u00f3 en 2019 con un taller piloto muy peque\u00f1o, de apenas un mes, que hicimos para ver c\u00f3mo funcionaba. En \u00e9l participaron veinte j\u00f3venes, chicas y chicos, de entre 16 y 23 a\u00f1os, que proced\u00edan de los centros del programa ASPA. De ese primer proyecto sali\u00f3 una pel\u00edcula que se llama <em>Las edades sensibles a la luz<\/em>, que est\u00e1 dirigida por los docentes del proyecto, Pedro Sara y Violeta Pag\u00e1n, ya que en un mes no hay tiempo para llevar un trabajo que permita que los j\u00f3venes se involucren en labores de producci\u00f3n y direcci\u00f3n. Se trata, siempre, de desarrollar un proyecto cinematogr\u00e1fico en colectivo, donde el objetivo no solamente sea la puesta en marcha de ese proyecto sino tambi\u00e9n la utilizaci\u00f3n del cine como herramienta para encontrarnos a nosotros mismos, para hablar sobre distintas problem\u00e1ticas. Un poco como dicen Pedro y Violeta: el cine como herramienta de sanaci\u00f3n. O sea que hay una parte del proyecto que mezcla el psicodrama y el trabajo espec\u00edficamente cinematogr\u00e1fico. Lo que es interesante es que desde el primer momento, desde la primera o segunda clase, se empieza a trabajar en t\u00e9rminos cinematogr\u00e1ficos. Se coge la c\u00e1mara, se empieza a rodar. A diferencia de otras escuelas m\u00e1s formales, aqu\u00ed no hay un programa dirigido sino que cada d\u00eda el programa se trabaja en funci\u00f3n de las necesidades que hayan y de lo que decida cada grupo.<\/p>\n\n\n\n<p>En el siguiente a\u00f1o, empezamos a trabajar en un programa de larga duraci\u00f3n. Lo que tenemos hoy en d\u00eda es un proyecto que se hace de octubre a junio, todos los d\u00edas de la semana, cuatro horas diarias. Tenemos un grupo de los lunes, mi\u00e9rcoles y viernes, que es el de los estudiantes que participan de la escuela por primera vez, y un grupo de los martes y los jueves, donde se forma una suerte de grupo de encuentro y de reencuentro, donde los participantes de otros a\u00f1os siguen desarrollando en colectivo sus proyectos cinematogr\u00e1ficos. Es un proyecto importante: la escuela se vuelve un lugar de refugio, de aprendizaje, de generaci\u00f3n de lazos y amistades, y tambi\u00e9n, para algunos de ellos, es la oportunidad de comenzar un desarrollo profesional. Esto es importante porque estamos hablando de comunidades que generalmente no tienen acceso a la formaci\u00f3n en las escuelas de cine. Muchos de ellos llegan aqu\u00ed interesados por el cine pero sinti\u00e9ndolo como algo un poco ajeno, sobre todo lo que es su producci\u00f3n y su desarrollo, y a lo largo de los meses de trabajo empiezan a sentirlo como algo propio. Ese proceso termina siendo bastante importante a nivel personal para cada uno de los involucrados, por sus cualidades transformadoras tanto para los participantes como para la propia instituci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/beatriz-1024x576.jpg\" alt=\"\" class=\"wp-image-7049\" width=\"540\" height=\"303\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/beatriz-1024x576.jpg 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/beatriz-300x169.jpg 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/beatriz-768x432.jpg 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/beatriz.jpg 1200w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/><figcaption class=\"wp-element-caption\">Beatriz Bartolom\u00e9 Herrera<\/figcaption><\/figure>\n\n\n\n<p><strong>M\u00e1s all\u00e1 de <\/strong><strong><em>Dentro Cine, <\/em><\/strong><strong>en Cineteca tambi\u00e9n llevan adelante el programa <\/strong><strong><em>CineZeta. <\/em><\/strong><strong>\u00bfEn qu\u00e9 consiste?<\/strong><\/p>\n\n\n\n<p>Se trata de un equipo de j\u00f3venes programadores, compuesto por diez personas. Ya vamos por la sexta convocatoria, y consiste en otorgar un espacio para que estos equipos, a\u00f1o a a\u00f1o, puedan desarrollar sus propias propuestas curatoriales y de programaci\u00f3n. Se les otorga un presupuesto y se lleva a cabo un seguimiento y una formaci\u00f3n con los integrantes del equipo. El objetivo principal es que las personas m\u00e1s j\u00f3venes, que de momento no han tenido la oportunidad de desarrollar una labor de programaci\u00f3n, puedan hacerlo desde una sala con todo el apoyo de una instituci\u00f3n como Cineteca. Otro de los objetivos es tambi\u00e9n que se lo pasen bien, que hagan amistades y que disfruten de la oportunidad. Una parte muy importante del proyecto es que <em>CineZeta<\/em> es una especie de germen, de espacio del que surgen luego no solo amistades sino tambi\u00e9n proyectos. Por ejemplo, los miembros de <em>CineZeta <\/em>de la cuarta convocatoria han formado un colectivo que se llama \u201cMedia distancia\u201d, en el que contin\u00faan sus actividades de programaci\u00f3n tanto en salas como en otros espacios. Por otro lado, una parte muy importante del programa tiene que ver con acercar el cine a generaciones m\u00e1s j\u00f3venes. Quienes estamos aqu\u00ed programando, l\u00f3gicamente, ya tenemos una edad, y a lo mejor venimos de tradiciones que, por mucho que nos queramos reciclar, son diferentes a la relaci\u00f3n que los j\u00f3venes tienen con el audiovisual hoy. Creemos que es muy importante que quienes pasan por <em>CineZeta <\/em>traigan esa mirada m\u00e1s joven y que, al mismo tiempo, dispongan un espacio atractivo para p\u00fablicos m\u00e1s j\u00f3venes, para que puedan participar de las actividades de Cineteca y conocer la instituci\u00f3n.&nbsp;<\/p>\n\n\n\n<p><strong>Viniendo de Argentina, donde no hay programas como estos ni dinero como el que me cont\u00e1s que les dan a los participantes para abonar <\/strong><strong><em>fees<\/em><\/strong><strong> \u2014ya que un <\/strong><strong><em>fee<\/em><\/strong><strong> es equivalente a un sueldo m\u00ednimo\u2014, quer\u00eda preguntarte, por un lado, c\u00f3mo los ayudan a administrarlo y, por otro lado, acerca de la formaci\u00f3n con la que los acompa\u00f1an: \u00bfdan alg\u00fan tipo de material te\u00f3rico con respecto a la historia del cine?<\/strong><\/p>\n\n\n\n<p>Aqu\u00ed se aprende programaci\u00f3n haciendo. Aprenden a programar en un marco institucional muy concreto: no es lo mismo programar para un festival que para un cine con una gesti\u00f3n privada. Aqu\u00ed trabajamos para una instituci\u00f3n p\u00fablica, que es una sala comercial pero muy particular, donde el principal objetivo no es econ\u00f3mico sino que se trata de ofrecer un servicio p\u00fablico. El aprendizaje de la programaci\u00f3n se produce en ese marco concreto. \u00bfC\u00f3mo lo hacemos? Cuando se forma el grupo de los diez participantes tenemos un mes en el que los distintos integrantes del equipo de programaci\u00f3n, de gesti\u00f3n y de comunicaci\u00f3n de Cineteca y Matadero tienen sesiones con el grupo, en el que se les habla del trabajo que hacemos y se les presentan las labores que como equipo van a tener que desarrollar. Este per\u00edodo de formaci\u00f3n es tambi\u00e9n un per\u00edodo de conocimiento, de crear grupo entre ellos. Una parte muy importante que permite que el proyecto vaya bien es que sepan organizarse entre s\u00ed, se lleven bien y hagan equipo para repartirse las tareas, ya que esto es un trabajo que se lleva a cabo de manera no remunerada. Siempre les recordamos que intenten que el peso del trabajo no sea demasiado y que no los quite de sus labores principales, sea el trabajo, el estudio o lo que fuera. Despu\u00e9s de este per\u00edodo se los pone a empezar con sus programaciones mensuales, con acompa\u00f1amiento constante. Nos mandamos mails, tenemos reuniones peri\u00f3dicas en las que nos juntamos, hablamos y nos cuentan las ideas que tienen para ese mes, las dificultades que tienen. El equipo de programadores se encarga de dise\u00f1ar la programaci\u00f3n con las propuestas de pel\u00edculas y de buscar las distribuidoras que tienen los derechos. Luego, la gesti\u00f3n administrativa la lleva el personal de Cineteca.&nbsp;<\/p>\n\n\n\n<p>En ese primer mes aprenden desde cuestiones art\u00edsticas en lo relativo a la programaci\u00f3n, junto al director art\u00edstico Luis E. Par\u00e9s y el programador Vicente Monroy, hasta cuestiones m\u00e1s administrativas como la gesti\u00f3n de copias o la comunicaci\u00f3n de las actividades. Estos \u00faltimos a\u00f1os hemos venido incorporando charlas formativas con programadores y programadoras. Invitamos a personas que se dedican a la programaci\u00f3n en distintos contextos \u2014festivales, otras instituciones, proyectos como el de Helena, con <em>Aulafilm<\/em><sup><a href=\"#nota2\">(2)<\/a><\/sup>\u2014 para que hablen desde su experiencia y su saber hacer con los integrantes del equipo. Esto permite que, mientras ellos llevan adelante sus programaciones, puedan hablar con estos programadores cara a cara, hacerles preguntas o compartir las problem\u00e1ticas con las que se enfrentan durante este proceso. Luego, en lo relativo a la teor\u00eda o la historia del cine no damos ninguna formaci\u00f3n espec\u00edfica. Tambi\u00e9n es verdad que el aprendizaje del cine no tiene por qu\u00e9 ser espec\u00edficamente reglado o sujeto a un canon preestablecido. Precisamente, el programa <em>CineZeta<\/em> est\u00e1 abierto a lenguajes m\u00e1s all\u00e1 del cine tradicional, por lo que confiamos un poco en el saber hacer y en la capacidad de los j\u00f3venes de mantener un di\u00e1logo con la cultura contempor\u00e1nea a partir de sus pr\u00e1cticas de consumo. El equipo est\u00e1 integrado por personas que en muchos casos s\u00ed tienen una educaci\u00f3n formal relacionada con el cine o el audiovisual, personas que vienen de escuelas de cinematograf\u00eda o estudios de comunicaci\u00f3n audiovisual. Pero siempre intentamos formar grupos heterog\u00e9neos en cuanto a sus disciplinas de procedencia, por lo que participan del proyecto personas que vienen de otras disciplinas human\u00edsticas, como la filosof\u00eda o las ciencias pol\u00edticas. Este a\u00f1o, por ejemplo, algunos vienen del campo de la psicolog\u00eda y de la ingenier\u00eda. Intentamos sacar al cine del caj\u00f3n de lo que es el marco hist\u00f3rico y te\u00f3rico tradicional y ponerlo siempre en di\u00e1logo y relaci\u00f3n con un contexto m\u00e1s amplio.<\/p>\n\n\n\n<p>Con respecto al presupuesto, se utiliza para los <em>fees<\/em> de las pel\u00edculas y, tambi\u00e9n, para los honorarios de las personas que quieran invitar. Porque la programaci\u00f3n de <em>CineZeta<\/em> no es exclusivamente la programaci\u00f3n de pel\u00edculas o de obras audiovisuales. Algunos equipos hacen presentaciones o di\u00e1logos con figuras contempor\u00e1neas relacionadas con la creaci\u00f3n cultural. Una vez, por ejemplo, uno de los participantes invit\u00f3 a la activista trans Samantha Hudson. Parte de los presupuestos se utiliza para pagar esos honorarios. Ellos lo manejan a\u00f1o a a\u00f1o seg\u00fan la programaci\u00f3n que decidan llevar adelante.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/Cineteca-Sala-Azcona-1.jpg\" alt=\"\" class=\"wp-image-7058\" width=\"537\" height=\"354\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/Cineteca-Sala-Azcona-1.jpg 694w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/Cineteca-Sala-Azcona-1-300x198.jpg 300w\" sizes=\"(max-width: 537px) 100vw, 537px\" \/><\/figure>\n\n\n\n<p><strong>Claro, me imagino que ayuda tambi\u00e9n que el presupuesto sea similar a\u00f1o a a\u00f1o. Si quisi\u00e9ramos llevar adelante algo as\u00ed en Argentina tendr\u00edamos un problema bastante grande con respecto a la cuesti\u00f3n inflacionaria.&nbsp;<\/strong><\/p>\n\n\n\n<p>S\u00ed, tambi\u00e9n hay una parte del aprendizaje que tiene que ver con aprender a negociar. Hubo equipos que lo han hecho s\u00faper bien, que han aprovechado el presentarse a las distribuidoras como un programa educativo, destinado al p\u00fablico joven en una instituci\u00f3n, y han conseguido verdaderas rebajas. Fueron muy habilidosos en eso. Contamos con un presupuesto digno, que permite el desarrollo de una programaci\u00f3n sin demasiados problemas. Tambi\u00e9n a veces queremos programar cosas que escapan al presupuesto que tenemos; siempre hay que tener un plan B. Parte del aprendizaje del programador es tener un control presupuestario. En nuestras reuniones peri\u00f3dicas vamos viendo c\u00f3mo van los gastos, si est\u00e1n muy justos o no, y en general no hemos tenido ning\u00fan problema.&nbsp;<\/p>\n\n\n\n<p><strong>Dado que no es com\u00fan conocer experiencias de formaci\u00f3n de programadores como esta, es interesante pensar que en ciertos contextos se ingresa a programar sin formaci\u00f3n espec\u00edfica, a veces por contactos o por trabajar bien en t\u00e9rminos pr\u00e1cticos. Y quiz\u00e1 esos nuevos programadores no tienen demasiado conocimiento sobre historia del cine ni distancia con respecto al cine contempor\u00e1neo, en t\u00e9rminos de que no poseen una mirada cr\u00edtica de las formas en que se produce y programa el cine hoy. J\u00f3venes que podr\u00edan traer una mirada fresca finalmente toman las mismas decisiones que tomar\u00edan sus antecesores. \u00bfC\u00f3mo podr\u00eda formarse una mirada diferencial en ese sentido?<\/strong><\/p>\n\n\n\n<p>Creo que a veces hay un malentendido entre la programaci\u00f3n y el programador, que es esto de que la programaci\u00f3n exprese un gusto personal. Por mi experiencia aqu\u00ed, la programaci\u00f3n no surge de la expresi\u00f3n personal de nadie en concreto \u2014aunque, evidentemente, nuestros gustos siempre est\u00e1n presentes, si bien nunca es lo que se expresa de manera principal en una programaci\u00f3n\u2014, en Cineteca al menos la programaci\u00f3n es algo que se hace en colectivo, en equipo, y que adem\u00e1s responde a muchas otras circunstancias. Muchas veces eliges una pel\u00edcula, no porque sea buena o te parezca buena, sino porque plantea preguntas relevantes, porque se relaciona bien con otras pel\u00edculas de la programaci\u00f3n, porque abre debates, porque tiene que ver con quienes vienen a verlas. Creo que, al final, el personalismo acaba diluy\u00e9ndose. Por supuesto, siempre hay l\u00edneas art\u00edsticas que marcan el ritmo o el paso.&nbsp;<\/p>\n\n\n\n<p>Esa necesidad de satisfacer a determinado grupo, que es del que t\u00fa dependes como programador cuando empiezas, es una pena. Tiene que ver con las condiciones muchas veces precarias que tiene el trabajo de la programaci\u00f3n y que se producen desde posiciones de personas que son <em>freelance<\/em> o aut\u00f3nomas y para quienes la continuidad de su trabajo depende de mantener ciertos lazos y de satisfacer a ciertas personas, sin pensar c\u00f3mo tu programaci\u00f3n satisface a lo mejor a un p\u00fablico o habla de determinados temas. Una de las ventajas de trabajar en una instituci\u00f3n p\u00fablica y de tener trabajos m\u00e1s estables es poder olvidarte un poco de esos condicionantes, por m\u00e1s que siempre hay muchos de esos factores en juego. Condiciones como esta permiten escaparse de este tipo de relaciones un poco perversas y pueden dar lugar a una programaci\u00f3n que se mire menos a s\u00ed misma y que mire un poco m\u00e1s hacia fuera.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/Equipo-de-Cinezeta-del-2021-deliberando-como-jurado-de-Documenta-Madrid-2021.-4-1024x682.jpg\" alt=\"\" class=\"wp-image-7065\" width=\"533\" height=\"355\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/Equipo-de-Cinezeta-del-2021-deliberando-como-jurado-de-Documenta-Madrid-2021.-4-1024x682.jpg 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/Equipo-de-Cinezeta-del-2021-deliberando-como-jurado-de-Documenta-Madrid-2021.-4-300x200.jpg 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/Equipo-de-Cinezeta-del-2021-deliberando-como-jurado-de-Documenta-Madrid-2021.-4-768x512.jpg 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/Equipo-de-Cinezeta-del-2021-deliberando-como-jurado-de-Documenta-Madrid-2021.-4-1536x1023.jpg 1536w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/Equipo-de-Cinezeta-del-2021-deliberando-como-jurado-de-Documenta-Madrid-2021.-4-2048x1365.jpg 2048w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/><\/figure>\n\n\n\n<p><strong>Si tuvieras que justificar la importancia de que se sigan llevando adelante estos programas frente a alguien que quiz\u00e1 no est\u00e1 tan en tema, \u00bfqu\u00e9 tipo de argumentos usar\u00edas, qu\u00e9 traer\u00edas a la mesa?<\/strong><\/p>\n\n\n\n<p>A veces para defender estas cosas lo mejor es buscar qu\u00e9 es aquello que tenemos en com\u00fan. Lo cierto es que el consumo de im\u00e1genes y la mediaci\u00f3n de nuestras relaciones a trav\u00e9s de pantallas es tan prevalente que todos, al final, tenemos una relaci\u00f3n muy directa con ellas. Lo que pasa es que esa relaci\u00f3n se ha vuelto casi transparente, y no acabamos de cuestionarla o interrogarla. La importancia de que una instituci\u00f3n p\u00fablica como Cineteca tenga un programa de formaci\u00f3n, de pensamiento y de producci\u00f3n cr\u00edtica tiene que ver con la necesidad de formarnos y de interrogar nuestra relaci\u00f3n con las im\u00e1genes, que es algo que muchas veces se da por hecho pero que realmente ni se ense\u00f1a ni se aprende en los centros educativos, a no ser que lleves una formaci\u00f3n espec\u00edfica. En l\u00edneas generales, no hay un aprendizaje sobre c\u00f3mo las obras audiovisuales tienen objetivos muy concretos, comunicando ideas o transmitiendo ideolog\u00edas muy espec\u00edficas. Entonces, a la hora de relacionarnos con ellas es importante que construyamos una relaci\u00f3n cr\u00edtica, que permita cuestionarlas. Esto no quiere decir que todas las im\u00e1genes intenten convencernos de algo, ya que no todo es propaganda. Pero s\u00ed todo es susceptible de ser cuestionado e interrogado, atravesado por una relaci\u00f3n consciente. Por eso, finalmente, es muy importante que las instituciones lleven a cabo programas formativos mientras que, al mismo tiempo, la propia programaci\u00f3n est\u00e9 impulsada por un planteamiento cr\u00edtico de lo que es la producci\u00f3n audiovisual contempor\u00e1nea y pasada, poniendo en relaci\u00f3n los diferentes contextos y pensando en la audiencia que no solo viene a ver, sino tambi\u00e9n a participar.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"7053\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/fuego-en-castilla-1024x576.jpg\" alt=\"\" class=\"wp-image-7053\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/fuego-en-castilla-1024x576.jpg 1024w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/fuego-en-castilla-300x169.jpg 300w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/fuego-en-castilla-768x432.jpg 768w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/fuego-en-castilla.jpg 1366w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"460\" height=\"375\" data-id=\"7052\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/SinFin.jpg\" alt=\"\" class=\"wp-image-7052\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/SinFin.jpg 460w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/SinFin-300x245.jpg 300w\" sizes=\"(max-width: 460px) 100vw, 460px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"244\" data-id=\"7051\" src=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/sin-fin_ok.jpg\" alt=\"\" class=\"wp-image-7051\" srcset=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/sin-fin_ok.jpg 400w, https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/sin-fin_ok-300x183.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/figure>\n<\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div style=\"height:24px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-small-font-size\"><strong>Notas:<\/strong><\/p>\n\n\n\n<p class=\"has-small-font-size\" id=\"nota1\"><strong>1<\/strong> La Cineteca es un complejo cinematogr\u00e1fico que funciona dentro de Matadero Madrid, un centro cultural multidisciplinar en el que se llevan adelante todo tipo de programas de formaci\u00f3n y exhibici\u00f3n art\u00edstica.<\/p>\n\n\n\n<p class=\"has-small-font-size\" id=\"nota2\"><strong>2<\/strong> Helena Fern\u00e1ndez, fundadora de Las Espigadoras, fue entrevistada para la secci\u00f3n &#8216;Cine en las aulas, aulas en el cine&#8217; (26\/11\/2022). La nota puede leerse <a href=\"https:\/\/taipeirevista.com\/index.php\/2022\/11\/26\/el-cine-conecta-con-dos-derechos-el-acceso-a-la-cultura-y-la-ciudadania-parte-del-trabajo-educativo-tiene-que-ver-con-esto-ya-que-condiciona-la-posible-libertad-de-nuestro-desarrollo-como-persona\/\">aqu\u00ed<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beatriz Bartolom\u00e9 Herrera es gestora cultural, docente e investigadora. Conversamos con ella para conocer los dos programas de formaci\u00f3n cinematogr\u00e1fica que gestiona en Cineteca: Dentro Cine, un proyecto experimental de educaci\u00f3n art\u00edstica para j\u00f3venes en situaci\u00f3n de vulnerabilidad, y CineZeta, uno de los pocos proyectos de formaci\u00f3n en programaci\u00f3n de cine de Iberoam\u00e9rica.<\/p>\n","protected":false},"author":2,"featured_media":7049,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[56],"tags":[1063,1059,997,1061,1060,1062],"class_list":{"0":"post-7047","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-educacion","8":"tag-aula-sin-fin","9":"tag-beatriz-bartolome-herrera","10":"tag-cine-en-las-aulas","11":"tag-cinezeta","12":"tag-dentro-cine","13":"tag-jose-val-del-omar"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cUna programaci\u00f3n que mire m\u00e1s hacia afuera\u201d. Beatriz Bartolom\u00e9 Herrera, coordinadora en Cineteca - TAIPEI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/taipeirevista.com\/index.php\/2023\/02\/10\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cUna programaci\u00f3n que mire m\u00e1s hacia afuera\u201d. Beatriz Bartolom\u00e9 Herrera, coordinadora en Cineteca - TAIPEI\" \/>\n<meta property=\"og:description\" content=\"Beatriz Bartolom\u00e9 Herrera es gestora cultural, docente e investigadora. Conversamos con ella para conocer los dos programas de formaci\u00f3n cinematogr\u00e1fica que gestiona en Cineteca: Dentro Cine, un proyecto experimental de educaci\u00f3n art\u00edstica para j\u00f3venes en situaci\u00f3n de vulnerabilidad, y CineZeta, uno de los pocos proyectos de formaci\u00f3n en programaci\u00f3n de cine de Iberoam\u00e9rica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/taipeirevista.com\/index.php\/2023\/02\/10\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\/\" \/>\n<meta property=\"og:site_name\" content=\"TAIPEI\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revistataipei\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-10T15:56:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-11T00:54:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/beatriz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Iv\u00e1n Bustinduy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@taipeicritica\" \/>\n<meta name=\"twitter:site\" content=\"@taipeicritica\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Iv\u00e1n Bustinduy\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2023\\\/02\\\/10\\\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2023\\\/02\\\/10\\\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\\\/\"},\"author\":{\"name\":\"Iv\u00e1n Bustinduy\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#\\\/schema\\\/person\\\/8f7642517bfc0525cd7deb8a46551158\"},\"headline\":\"\u201cUna programaci\u00f3n que mire m\u00e1s hacia afuera\u201d. Beatriz Bartolom\u00e9 Herrera, coordinadora en Cineteca\",\"datePublished\":\"2023-02-10T15:56:42+00:00\",\"dateModified\":\"2023-02-11T00:54:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2023\\\/02\\\/10\\\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\\\/\"},\"wordCount\":3095,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2023\\\/02\\\/10\\\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/taipeirevista.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/beatriz.jpg\",\"keywords\":[\"Aula Sin Fin\",\"Beatriz Bartolom\u00e9 Herrera\",\"Cine en las aulas\",\"CineZeta\",\"Dentro Cine\",\"Jos\u00e9 Val del Omar\"],\"articleSection\":[\"Educaci\u00f3n\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2023\\\/02\\\/10\\\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2023\\\/02\\\/10\\\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\\\/\",\"url\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2023\\\/02\\\/10\\\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\\\/\",\"name\":\"\u201cUna programaci\u00f3n que mire m\u00e1s hacia afuera\u201d. Beatriz Bartolom\u00e9 Herrera, coordinadora en Cineteca - TAIPEI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2023\\\/02\\\/10\\\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2023\\\/02\\\/10\\\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/taipeirevista.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/beatriz.jpg\",\"datePublished\":\"2023-02-10T15:56:42+00:00\",\"dateModified\":\"2023-02-11T00:54:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2023\\\/02\\\/10\\\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2023\\\/02\\\/10\\\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2023\\\/02\\\/10\\\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/taipeirevista.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/beatriz.jpg\",\"contentUrl\":\"https:\\\/\\\/taipeirevista.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/beatriz.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/2023\\\/02\\\/10\\\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/taipeirevista.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cUna programaci\u00f3n que mire m\u00e1s hacia afuera\u201d. Beatriz Bartolom\u00e9 Herrera, coordinadora en Cineteca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#website\",\"url\":\"https:\\\/\\\/taipeirevista.com\\\/\",\"name\":\"TAIPEI\",\"description\":\"Cr\u00edtica de cine\",\"publisher\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/taipeirevista.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#organization\",\"name\":\"Taipei \\\/ Cr\u00edtica de cine\",\"url\":\"https:\\\/\\\/taipeirevista.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/taipeirevista.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/TAIPEI-LOGO-1.1-SIN-GRIS.png\",\"contentUrl\":\"https:\\\/\\\/taipeirevista.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/TAIPEI-LOGO-1.1-SIN-GRIS.png\",\"width\":599,\"height\":599,\"caption\":\"Taipei \\\/ Cr\u00edtica de cine\"},\"image\":{\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/revistataipei\",\"https:\\\/\\\/x.com\\\/taipeicritica\",\"https:\\\/\\\/www.instagram.com\\\/taipeicritica\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/taipeirevista.com\\\/#\\\/schema\\\/person\\\/8f7642517bfc0525cd7deb8a46551158\",\"name\":\"Iv\u00e1n Bustinduy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33a83bcd8813d5df410ca38aad13b35c97807dbcd765337fc381f40b743c1a75?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33a83bcd8813d5df410ca38aad13b35c97807dbcd765337fc381f40b743c1a75?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/33a83bcd8813d5df410ca38aad13b35c97807dbcd765337fc381f40b743c1a75?s=96&d=mm&r=g\",\"caption\":\"Iv\u00e1n Bustinduy\"},\"description\":\"Naci\u00f3 en Buenos Aires en 1997. Se form\u00f3 como realizador cinematogr\u00e1fico y profesor en la Universidad del Cine (FUC), donde trabaja como docente. Dirigi\u00f3 los cortometrajes El segundo hombre (2021), ganador del Premio M\u00e9li\u00e8s en el Festival de Cine de Mar del Plata, y Carga animal (2022), con estreno en BAFICI, P\u00d6FF Shorts y Palm Springs. Es coordinador del Colectivo Rutemberg, productora con base en Buenos Aires, y de TAIPEI \\\/ Cr\u00edtica de cine, donde escribe sobre cine y educaci\u00f3n. Trabaja como director de programaci\u00f3n en Guayaba, una plataforma de cine latinoamericano. Actualmente cursa el M\u00e1ster de Comisariado en El\u00edas Querejeta Zine Eskola (EQZE) mientras desarrolla Tiempo fuera, su \u00f3pera prima. Contacto: bustinduyivan@gmail.com.\",\"sameAs\":[\"http:\\\/\\\/taipeirevista.com\"],\"url\":\"https:\\\/\\\/taipeirevista.com\\\/index.php\\\/author\\\/ivanb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cUna programaci\u00f3n que mire m\u00e1s hacia afuera\u201d. Beatriz Bartolom\u00e9 Herrera, coordinadora en Cineteca - TAIPEI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/taipeirevista.com\/index.php\/2023\/02\/10\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\/","og_locale":"es_ES","og_type":"article","og_title":"\u201cUna programaci\u00f3n que mire m\u00e1s hacia afuera\u201d. Beatriz Bartolom\u00e9 Herrera, coordinadora en Cineteca - TAIPEI","og_description":"Beatriz Bartolom\u00e9 Herrera es gestora cultural, docente e investigadora. Conversamos con ella para conocer los dos programas de formaci\u00f3n cinematogr\u00e1fica que gestiona en Cineteca: Dentro Cine, un proyecto experimental de educaci\u00f3n art\u00edstica para j\u00f3venes en situaci\u00f3n de vulnerabilidad, y CineZeta, uno de los pocos proyectos de formaci\u00f3n en programaci\u00f3n de cine de Iberoam\u00e9rica.","og_url":"https:\/\/taipeirevista.com\/index.php\/2023\/02\/10\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\/","og_site_name":"TAIPEI","article_publisher":"https:\/\/www.facebook.com\/revistataipei","article_published_time":"2023-02-10T15:56:42+00:00","article_modified_time":"2023-02-11T00:54:34+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/beatriz.jpg","type":"image\/jpeg"}],"author":"Iv\u00e1n Bustinduy","twitter_card":"summary_large_image","twitter_creator":"@taipeicritica","twitter_site":"@taipeicritica","twitter_misc":{"Escrito por":"Iv\u00e1n Bustinduy","Tiempo de lectura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/taipeirevista.com\/index.php\/2023\/02\/10\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\/#article","isPartOf":{"@id":"https:\/\/taipeirevista.com\/index.php\/2023\/02\/10\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\/"},"author":{"name":"Iv\u00e1n Bustinduy","@id":"https:\/\/taipeirevista.com\/#\/schema\/person\/8f7642517bfc0525cd7deb8a46551158"},"headline":"\u201cUna programaci\u00f3n que mire m\u00e1s hacia afuera\u201d. Beatriz Bartolom\u00e9 Herrera, coordinadora en Cineteca","datePublished":"2023-02-10T15:56:42+00:00","dateModified":"2023-02-11T00:54:34+00:00","mainEntityOfPage":{"@id":"https:\/\/taipeirevista.com\/index.php\/2023\/02\/10\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\/"},"wordCount":3095,"commentCount":0,"publisher":{"@id":"https:\/\/taipeirevista.com\/#organization"},"image":{"@id":"https:\/\/taipeirevista.com\/index.php\/2023\/02\/10\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\/#primaryimage"},"thumbnailUrl":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/beatriz.jpg","keywords":["Aula Sin Fin","Beatriz Bartolom\u00e9 Herrera","Cine en las aulas","CineZeta","Dentro Cine","Jos\u00e9 Val del Omar"],"articleSection":["Educaci\u00f3n"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/taipeirevista.com\/index.php\/2023\/02\/10\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/taipeirevista.com\/index.php\/2023\/02\/10\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\/","url":"https:\/\/taipeirevista.com\/index.php\/2023\/02\/10\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\/","name":"\u201cUna programaci\u00f3n que mire m\u00e1s hacia afuera\u201d. Beatriz Bartolom\u00e9 Herrera, coordinadora en Cineteca - TAIPEI","isPartOf":{"@id":"https:\/\/taipeirevista.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/taipeirevista.com\/index.php\/2023\/02\/10\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\/#primaryimage"},"image":{"@id":"https:\/\/taipeirevista.com\/index.php\/2023\/02\/10\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\/#primaryimage"},"thumbnailUrl":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/beatriz.jpg","datePublished":"2023-02-10T15:56:42+00:00","dateModified":"2023-02-11T00:54:34+00:00","breadcrumb":{"@id":"https:\/\/taipeirevista.com\/index.php\/2023\/02\/10\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/taipeirevista.com\/index.php\/2023\/02\/10\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/taipeirevista.com\/index.php\/2023\/02\/10\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\/#primaryimage","url":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/beatriz.jpg","contentUrl":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/beatriz.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/taipeirevista.com\/index.php\/2023\/02\/10\/una-programacion-que-mire-mas-hacia-afuera-beatriz-bartolome-herrera-coordinadora-en-cineteca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/taipeirevista.com\/"},{"@type":"ListItem","position":2,"name":"\u201cUna programaci\u00f3n que mire m\u00e1s hacia afuera\u201d. Beatriz Bartolom\u00e9 Herrera, coordinadora en Cineteca"}]},{"@type":"WebSite","@id":"https:\/\/taipeirevista.com\/#website","url":"https:\/\/taipeirevista.com\/","name":"TAIPEI","description":"Cr\u00edtica de cine","publisher":{"@id":"https:\/\/taipeirevista.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/taipeirevista.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/taipeirevista.com\/#organization","name":"Taipei \/ Cr\u00edtica de cine","url":"https:\/\/taipeirevista.com\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/taipeirevista.com\/#\/schema\/logo\/image\/","url":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/08\/TAIPEI-LOGO-1.1-SIN-GRIS.png","contentUrl":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2022\/08\/TAIPEI-LOGO-1.1-SIN-GRIS.png","width":599,"height":599,"caption":"Taipei \/ Cr\u00edtica de cine"},"image":{"@id":"https:\/\/taipeirevista.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/revistataipei","https:\/\/x.com\/taipeicritica","https:\/\/www.instagram.com\/taipeicritica\/"]},{"@type":"Person","@id":"https:\/\/taipeirevista.com\/#\/schema\/person\/8f7642517bfc0525cd7deb8a46551158","name":"Iv\u00e1n Bustinduy","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/33a83bcd8813d5df410ca38aad13b35c97807dbcd765337fc381f40b743c1a75?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/33a83bcd8813d5df410ca38aad13b35c97807dbcd765337fc381f40b743c1a75?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/33a83bcd8813d5df410ca38aad13b35c97807dbcd765337fc381f40b743c1a75?s=96&d=mm&r=g","caption":"Iv\u00e1n Bustinduy"},"description":"Naci\u00f3 en Buenos Aires en 1997. Se form\u00f3 como realizador cinematogr\u00e1fico y profesor en la Universidad del Cine (FUC), donde trabaja como docente. Dirigi\u00f3 los cortometrajes El segundo hombre (2021), ganador del Premio M\u00e9li\u00e8s en el Festival de Cine de Mar del Plata, y Carga animal (2022), con estreno en BAFICI, P\u00d6FF Shorts y Palm Springs. Es coordinador del Colectivo Rutemberg, productora con base en Buenos Aires, y de TAIPEI \/ Cr\u00edtica de cine, donde escribe sobre cine y educaci\u00f3n. Trabaja como director de programaci\u00f3n en Guayaba, una plataforma de cine latinoamericano. Actualmente cursa el M\u00e1ster de Comisariado en El\u00edas Querejeta Zine Eskola (EQZE) mientras desarrolla Tiempo fuera, su \u00f3pera prima. Contacto: bustinduyivan@gmail.com.","sameAs":["http:\/\/taipeirevista.com"],"url":"https:\/\/taipeirevista.com\/index.php\/author\/ivanb\/"}]}},"jetpack_featured_media_url":"https:\/\/taipeirevista.com\/wp-content\/uploads\/2023\/02\/beatriz.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/posts\/7047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/comments?post=7047"}],"version-history":[{"count":8,"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/posts\/7047\/revisions"}],"predecessor-version":[{"id":7070,"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/posts\/7047\/revisions\/7070"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/media\/7049"}],"wp:attachment":[{"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/media?parent=7047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/categories?post=7047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/taipeirevista.com\/index.php\/wp-json\/wp\/v2\/tags?post=7047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}